{"id":32491,"date":"2020-05-26T14:46:50","date_gmt":"2020-05-26T12:46:50","guid":{"rendered":"https:\/\/wordpress-783423-2671269.cloudwaysapps.com\/?p=32491"},"modified":"2022-05-13T07:45:49","modified_gmt":"2022-05-13T05:45:49","slug":"26-mai-2020-smt-scharf-ag-haelt-erste-virtuelle-hauptversammlung-erfolgreich-ab","status":"publish","type":"post","link":"https:\/\/dev.cometis.de\/de\/26-mai-2020-smt-scharf-ag-haelt-erste-virtuelle-hauptversammlung-erfolgreich-ab\/","title":{"rendered":"26. Mai 2020 | SMT Scharf AG h\u00e4lt erste virtuelle Hauptversammlung erfolgreich ab"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;section&#8220; _builder_version=&#8220;4.16&#8243; da_disable_devices=&#8220;off|off|off&#8220; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row column_structure=&#8220;1_2,1_2&#8243; column_padding_mobile=&#8220;on&#8220; admin_label=&#8220;Zeile&#8220; _builder_version=&#8220;4.17.3&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; width=&#8220;100%&#8220; custom_padding=&#8220;0px|0px|0px|0px|true|true&#8220; hover_enabled=&#8220;0&#8243; make_fullwidth=&#8220;off&#8220; use_custom_width=&#8220;off&#8220; width_unit=&#8220;on&#8220; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Schaltfl\u00e4che %22zur\u00fcck zum Archiv%22&#8243; _builder_version=&#8220;4.16&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; text_orientation=&#8220;left&#8220; use_border_color=&#8220;off&#8220; border_color=&#8220;#ffffff&#8220; border_style=&#8220;solid&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<style> .zur\u00fcckbutton:before {display: inline-block; font-family: \"ETmodules\"; content: \"\\4a\"; color: #00225f; margin-right: 7px;} .zur\u00fcckbutton:hover:before {display: inline-block; font-family: \"ETmodules\"; content: \"\\4a\"; color: #d85710; margin-right: 7px;}<\/style>\n<h1>Corporate News<\/h1>\n<p><a class=\"zur\u00fcckbutton\" href=\"https:\/\/dev.cometis.de\/veroeffentlichungsarchiv-smt-scharf\">zum Archiv<\/a><br \/>\n[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/dev.cometis.de\/wp-content\/uploads\/2018\/08\/SMT_Logo_2011_ohne-Claim-01.png&#8220; align=&#8220;right&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;center&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;Logo&#8220; _builder_version=&#8220;4.16&#8243; use_border_color=&#8220;off&#8220; border_color=&#8220;#ffffff&#8220; border_style=&#8220;solid&#8220; animation=&#8220;off&#8220; sticky=&#8220;off&#8220; always_center_on_mobile=&#8220;on&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8220;row&#8220; _builder_version=&#8220;4.17.3&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; width=&#8220;100%&#8220; custom_padding=&#8220;0px|0px|0px|0px|true|true&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Text&#8220; _builder_version=&#8220;4.16&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; text_orientation=&#8220;left&#8220; use_border_color=&#8220;off&#8220; border_color=&#8220;#ffffff&#8220; border_style=&#8220;solid&#8220; saved_tabs=&#8220;all&#8220; global_colors_info=&#8220;{}&#8220;]<strong>SMT Scharf AG h\u00e4lt erste virtuelle Hauptversammlung erfolgreich ab &nbsp;&nbsp;<\/strong><\/p>\n<ul>\n<li><strong>Vorstand und Aufsichtsrat mit gro\u00dfer Mehrheit f\u00fcr Gesch\u00e4ftsjahr 2019 entlastet<\/strong><\/li>\n<li><strong>Pr\u00e4senz des vertretenen Grundkapitals bei<\/strong> <strong>36,28%<\/strong><\/li>\n<\/ul>\n<p>Hamm, 26. Mai 2020 \u2013 Die SMT Scharf AG (WKN 575198, ISIN DE0005751986), ein weltweit f\u00fchrender Anbieter f\u00fcr kundenindividuelle Transportl\u00f6sungen und Logistiksysteme f\u00fcr den Untertagebergbau, hat am heutigen Dienstag ihre ordentliche Hauptversammlung 2020 erfolgreich durchgef\u00fchrt. Auf Grundlage des vom Gesetzgeber verabschiedeten Gesetzes zur Abmilderung der Folgen der COVID-19-Pandemie (C19-AuswBekG) fand diese als virtuelle Hauptversammlung statt. Die Pr\u00e4senz des vertretenen Grundkapitals lag bei rund 36,28%. S\u00e4mtliche Tagesordnungspunkte wurden mit gro\u00dfer Mehrheit verabschiedet.<\/p>\n<p>Im Rahmen der Hauptversammlung berichtete der Vorstand \u00fcber die operative und strategische Entwicklung der SMT Scharf AG im Gesch\u00e4ftsjahr 2019, das durch ein deutliches Umsatz- und Ergebniswachstum gepr\u00e4gt war. So hat das Unternehmen verschiedene strategische Initiativen f\u00fcr k\u00fcnftiges Wachstum vorangetrieben, darunter der Erwerb der ser elektronik GmbH, die auf elektronische Steuerungen spezialisiert ist, sowie der fr\u00fchzeitig eingeleitete Zulassungsprozess von Maschinen f\u00fcr den chinesischen Markt, wo im Bergbau ab 2021 die neuen China-III-Vorgaben gelten. Ebenso gab der Vorstand einen Ausblick auf das laufende Gesch\u00e4ftsjahr 2020, das bislang wesentlich durch die Corona-Pandemie und den damit verbundenen allgemeinen wirtschaftlichen Folgen und Einschr\u00e4nkungen in den Bergbaum\u00e4rkten weltweit gepr\u00e4gt war.<\/p>\n<p>Zum Abschlusspr\u00fcfer f\u00fcr das Gesch\u00e4ftsjahr 2020 wurde die R\u00f6dl &amp; Partner GmbH Wirtschaftspr\u00fcfungsgesellschaft Steuerberatungsgesellschaft, Niederlassung K\u00f6ln, bestellt.<\/p>\n<p>Die detaillierten Abstimmungsergebnisse zu den jeweiligen Tagesordnungspunkten sind in K\u00fcrze auf der Webseite unter www.smtscharf.de im Investor-Relations-Bereich abrufbar.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Unternehmensprofil<\/strong><\/p>\n<p>Die SMT Scharf Gruppe entwickelt, baut und wartet Transportausr\u00fcstungen f\u00fcr den Bergbau unter Tage sowie f\u00fcr Tunnelbaustellen. Hauptprodukt sind entgleisungssichere Bahnsysteme, die weltweit vor allem in Steinkohlebergwerken sowie beim Abbau von Gold, Platin und anderen Erzen unter Tage eingesetzt werden. Sie transportieren dort Material und Personal bis zu einer Nutzlast von 48 Tonnen auf Strecken mit Steigungen bis zu 30 Grad. Daneben beliefert SMT Scharf den Bergbau mit Sesselliften. Zudem geh\u00f6ren seit 2018 gummibereifte Diesel- und Elektrofahrzeuge f\u00fcr den Berg- und Tunnelbau, darunter Fahrlader, Scherenarbeitsb\u00fchnen oder Untertage-LKWs, zum vielf\u00e4ltigen Portfolio von SMT Scharf. Im Zuge der weiteren Diversifizierung des Gesch\u00e4fts wurde seit 2019 das Lieferspektrum erfolgreich um elektronische Komponenten und Steuerungen f\u00fcr den Bergbau und andere Industrien erg\u00e4nzt. Insgesamt verf\u00fcgt die SMT Scharf Gruppe \u00fcber eigene Gesellschaften in acht L\u00e4ndern sowie weltweite Handelsvertretungen. Einen Gro\u00dfteil der Ums\u00e4tze erzielt SMT Scharf in den wachsenden Auslandsm\u00e4rkten wie China, Russland, Polen und S\u00fcdafrika. Die SMT Scharf AG ist seit dem Jahr 2007 im Prime Standard (Regulierter Markt) der Frankfurter Wertpapierb\u00f6rse notiert.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Kontakt<\/strong><\/p>\n<p>Investor Relations<br \/>\ncometis AG<br \/>\nThorben Burbach<br \/>\nTel: +49(0)611 &#8211; 205855-23<br \/>\nFax: +49(0)611 &#8211; 205855-66<br \/>\nE-Mail: burbach@dev.cometis.de<br \/>\n[\/et_pb_text][et_pb_text admin_label=&#8220;Schaltfl\u00e4che %22Beitrag als PDF%22&#8243; _builder_version=&#8220;4.16&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; text_orientation=&#8220;left&#8220; use_border_color=&#8220;off&#8220; border_color=&#8220;#ffffff&#8220; border_style=&#8220;solid&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<div class=\"leseprobe-archiv\"><a title=\"Beitrag als PDF\" href=\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2020\/05\/200526_SMT_Scharf_CN_HV_2020.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Beitrag als PDF<\/a><\/div>\n<style> .leseprobe-archiv {color: #00225f !important; border-color: #00225f; position: relative; padding: 0.3em 1em; border: 1px solid; -webkit-border-radius: 3px; -moz-border-radius: 3px; border-radius: 3px; -webkit-transition: all 0.2s; -moz-transition: all 0.2s; transition: all 0.2s; padding:10px; width: 19%; text-align: center; margin-right: 10px; float:left;} .leseprobe-archiv:hover {background-color: #eee; border-color: #ffffff; cursor: pointer;}<\/style>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Corporate News zum Archiv SMT Scharf AG h\u00e4lt erste virtuelle Hauptversammlung erfolgreich ab &nbsp;&nbsp; Vorstand und Aufsichtsrat mit gro\u00dfer Mehrheit f\u00fcr Gesch\u00e4ftsjahr 2019 entlastet Pr\u00e4senz des vertretenen Grundkapitals bei 36,28% Hamm, 26. Mai 2020 \u2013 Die SMT Scharf AG (WKN 575198, ISIN DE0005751986), ein weltweit f\u00fchrender Anbieter f\u00fcr kundenindividuelle Transportl\u00f6sungen und Logistiksysteme f\u00fcr den Untertagebergbau, [&hellip;]<\/p>\n","protected":false},"author":24813,"featured_media":54373,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[447,272],"tags":[496],"class_list":["post-32491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-smt-scharf-ag-corporate-news","tag-496"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>26. Mai 2020 | SMT Scharf AG h\u00e4lt erste virtuelle Hauptversammlung erfolgreich ab - cometis AG<\/title>\n<meta name=\"description\" content=\"Die SMT Scharf AG (WKN 575198, ISIN DE0005751986), ein weltweit f\u00fchrender Anbieter f\u00fcr kundenindividuelle Transportl\u00f6sungen und Logistiksysteme f\u00fcr den Untertagebergbau, hat am heutigen Dienstag ihre ordentliche Hauptversammlung 2020 erfolgreich durchgef\u00fchrt.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"26. Mai 2020 | SMT Scharf AG h\u00e4lt erste virtuelle Hauptversammlung erfolgreich ab - cometis AG\" \/>\n<meta property=\"og:description\" content=\"Die SMT Scharf AG (WKN 575198, ISIN DE0005751986), ein weltweit f\u00fchrender Anbieter f\u00fcr kundenindividuelle Transportl\u00f6sungen und Logistiksysteme f\u00fcr den Untertagebergbau, hat am heutigen Dienstag ihre ordentliche Hauptversammlung 2020 erfolgreich durchgef\u00fchrt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.cometis.de\/de\/26-mai-2020-smt-scharf-ag-haelt-erste-virtuelle-hauptversammlung-erfolgreich-ab\/\" \/>\n<meta property=\"og:site_name\" content=\"cometis AG\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-26T12:46:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-13T05:45:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Assistenz cometis AG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Assistenz cometis AG\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.cometis.de\/de\/26-mai-2020-smt-scharf-ag-haelt-erste-virtuelle-hauptversammlung-erfolgreich-ab\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/26-mai-2020-smt-scharf-ag-haelt-erste-virtuelle-hauptversammlung-erfolgreich-ab\/\"},\"author\":{\"name\":\"Assistenz cometis AG\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/0f6ec71e9167dd48a24950f3cc6b2003\"},\"headline\":\"26. Mai 2020 | SMT Scharf AG h\u00e4lt erste virtuelle Hauptversammlung erfolgreich ab\",\"datePublished\":\"2020-05-26T12:46:50+00:00\",\"dateModified\":\"2022-05-13T05:45:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/26-mai-2020-smt-scharf-ag-haelt-erste-virtuelle-hauptversammlung-erfolgreich-ab\/\"},\"wordCount\":858,\"publisher\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/26-mai-2020-smt-scharf-ag-haelt-erste-virtuelle-hauptversammlung-erfolgreich-ab\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg\",\"keywords\":[\"2020\"],\"articleSection\":[\"News\",\"SMT Scharf AG Corporate News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.cometis.de\/de\/26-mai-2020-smt-scharf-ag-haelt-erste-virtuelle-hauptversammlung-erfolgreich-ab\/\",\"url\":\"https:\/\/dev.cometis.de\/de\/26-mai-2020-smt-scharf-ag-haelt-erste-virtuelle-hauptversammlung-erfolgreich-ab\/\",\"name\":\"26. Mai 2020 | SMT Scharf AG h\u00e4lt erste virtuelle Hauptversammlung erfolgreich ab - cometis AG\",\"isPartOf\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/26-mai-2020-smt-scharf-ag-haelt-erste-virtuelle-hauptversammlung-erfolgreich-ab\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/26-mai-2020-smt-scharf-ag-haelt-erste-virtuelle-hauptversammlung-erfolgreich-ab\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg\",\"datePublished\":\"2020-05-26T12:46:50+00:00\",\"dateModified\":\"2022-05-13T05:45:49+00:00\",\"description\":\"Die SMT Scharf AG (WKN 575198, ISIN DE0005751986), ein weltweit f\u00fchrender Anbieter f\u00fcr kundenindividuelle Transportl\u00f6sungen und Logistiksysteme f\u00fcr den Untertagebergbau, hat am heutigen Dienstag ihre ordentliche Hauptversammlung 2020 erfolgreich durchgef\u00fchrt.\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.cometis.de\/de\/26-mai-2020-smt-scharf-ag-haelt-erste-virtuelle-hauptversammlung-erfolgreich-ab\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dev.cometis.de\/de\/26-mai-2020-smt-scharf-ag-haelt-erste-virtuelle-hauptversammlung-erfolgreich-ab\/#primaryimage\",\"url\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg\",\"contentUrl\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg\",\"caption\":\"Icon Newsroom_news\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#website\",\"url\":\"https:\/\/dev.cometis.de\/de\/\",\"name\":\"cometis AG\",\"description\":\"Deutschlands f\u00fchrende Investor Relations Agentur\",\"publisher\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.cometis.de\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#organization\",\"name\":\"cometis AG\",\"alternateName\":\"Deutschlands f\u00fchrende Investor Relations Agentur\",\"url\":\"https:\/\/dev.cometis.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/01\/Cometis-Mobile-Logo-1.png\",\"contentUrl\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/01\/Cometis-Mobile-Logo-1.png\",\"width\":171,\"height\":31,\"caption\":\"cometis AG\"},\"image\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/0f6ec71e9167dd48a24950f3cc6b2003\",\"name\":\"Assistenz cometis AG\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d9db77bcddbfa0c99848135c21ae5b93?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d9db77bcddbfa0c99848135c21ae5b93?s=96&d=mm&r=g\",\"caption\":\"Assistenz cometis AG\"},\"url\":\"https:\/\/dev.cometis.de\/de\/author\/assistenz-cometis-ag\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"26. Mai 2020 | SMT Scharf AG h\u00e4lt erste virtuelle Hauptversammlung erfolgreich ab - cometis AG","description":"Die SMT Scharf AG (WKN 575198, ISIN DE0005751986), ein weltweit f\u00fchrender Anbieter f\u00fcr kundenindividuelle Transportl\u00f6sungen und Logistiksysteme f\u00fcr den Untertagebergbau, hat am heutigen Dienstag ihre ordentliche Hauptversammlung 2020 erfolgreich durchgef\u00fchrt.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"26. Mai 2020 | SMT Scharf AG h\u00e4lt erste virtuelle Hauptversammlung erfolgreich ab - cometis AG","og_description":"Die SMT Scharf AG (WKN 575198, ISIN DE0005751986), ein weltweit f\u00fchrender Anbieter f\u00fcr kundenindividuelle Transportl\u00f6sungen und Logistiksysteme f\u00fcr den Untertagebergbau, hat am heutigen Dienstag ihre ordentliche Hauptversammlung 2020 erfolgreich durchgef\u00fchrt.","og_url":"https:\/\/dev.cometis.de\/de\/26-mai-2020-smt-scharf-ag-haelt-erste-virtuelle-hauptversammlung-erfolgreich-ab\/","og_site_name":"cometis AG","article_published_time":"2020-05-26T12:46:50+00:00","article_modified_time":"2022-05-13T05:45:49+00:00","og_image":[{"url":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg","width":1,"height":1,"type":"image\/png"}],"author":"Assistenz cometis AG","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Assistenz cometis AG","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.cometis.de\/de\/26-mai-2020-smt-scharf-ag-haelt-erste-virtuelle-hauptversammlung-erfolgreich-ab\/#article","isPartOf":{"@id":"https:\/\/dev.cometis.de\/de\/26-mai-2020-smt-scharf-ag-haelt-erste-virtuelle-hauptversammlung-erfolgreich-ab\/"},"author":{"name":"Assistenz cometis AG","@id":"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/0f6ec71e9167dd48a24950f3cc6b2003"},"headline":"26. Mai 2020 | SMT Scharf AG h\u00e4lt erste virtuelle Hauptversammlung erfolgreich ab","datePublished":"2020-05-26T12:46:50+00:00","dateModified":"2022-05-13T05:45:49+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.cometis.de\/de\/26-mai-2020-smt-scharf-ag-haelt-erste-virtuelle-hauptversammlung-erfolgreich-ab\/"},"wordCount":858,"publisher":{"@id":"https:\/\/dev.cometis.de\/de\/#organization"},"image":{"@id":"https:\/\/dev.cometis.de\/de\/26-mai-2020-smt-scharf-ag-haelt-erste-virtuelle-hauptversammlung-erfolgreich-ab\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg","keywords":["2020"],"articleSection":["News","SMT Scharf AG Corporate News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/dev.cometis.de\/de\/26-mai-2020-smt-scharf-ag-haelt-erste-virtuelle-hauptversammlung-erfolgreich-ab\/","url":"https:\/\/dev.cometis.de\/de\/26-mai-2020-smt-scharf-ag-haelt-erste-virtuelle-hauptversammlung-erfolgreich-ab\/","name":"26. Mai 2020 | SMT Scharf AG h\u00e4lt erste virtuelle Hauptversammlung erfolgreich ab - cometis AG","isPartOf":{"@id":"https:\/\/dev.cometis.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.cometis.de\/de\/26-mai-2020-smt-scharf-ag-haelt-erste-virtuelle-hauptversammlung-erfolgreich-ab\/#primaryimage"},"image":{"@id":"https:\/\/dev.cometis.de\/de\/26-mai-2020-smt-scharf-ag-haelt-erste-virtuelle-hauptversammlung-erfolgreich-ab\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg","datePublished":"2020-05-26T12:46:50+00:00","dateModified":"2022-05-13T05:45:49+00:00","description":"Die SMT Scharf AG (WKN 575198, ISIN DE0005751986), ein weltweit f\u00fchrender Anbieter f\u00fcr kundenindividuelle Transportl\u00f6sungen und Logistiksysteme f\u00fcr den Untertagebergbau, hat am heutigen Dienstag ihre ordentliche Hauptversammlung 2020 erfolgreich durchgef\u00fchrt.","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.cometis.de\/de\/26-mai-2020-smt-scharf-ag-haelt-erste-virtuelle-hauptversammlung-erfolgreich-ab\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dev.cometis.de\/de\/26-mai-2020-smt-scharf-ag-haelt-erste-virtuelle-hauptversammlung-erfolgreich-ab\/#primaryimage","url":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg","contentUrl":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg","caption":"Icon Newsroom_news"},{"@type":"WebSite","@id":"https:\/\/dev.cometis.de\/de\/#website","url":"https:\/\/dev.cometis.de\/de\/","name":"cometis AG","description":"Deutschlands f\u00fchrende Investor Relations Agentur","publisher":{"@id":"https:\/\/dev.cometis.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.cometis.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dev.cometis.de\/de\/#organization","name":"cometis AG","alternateName":"Deutschlands f\u00fchrende Investor Relations Agentur","url":"https:\/\/dev.cometis.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dev.cometis.de\/de\/#\/schema\/logo\/image\/","url":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/01\/Cometis-Mobile-Logo-1.png","contentUrl":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/01\/Cometis-Mobile-Logo-1.png","width":171,"height":31,"caption":"cometis AG"},"image":{"@id":"https:\/\/dev.cometis.de\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/0f6ec71e9167dd48a24950f3cc6b2003","name":"Assistenz cometis AG","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d9db77bcddbfa0c99848135c21ae5b93?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d9db77bcddbfa0c99848135c21ae5b93?s=96&d=mm&r=g","caption":"Assistenz cometis AG"},"url":"https:\/\/dev.cometis.de\/de\/author\/assistenz-cometis-ag\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/posts\/32491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/users\/24813"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/comments?post=32491"}],"version-history":[{"count":3,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/posts\/32491\/revisions"}],"predecessor-version":[{"id":84151,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/posts\/32491\/revisions\/84151"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/media\/54373"}],"wp:attachment":[{"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/media?parent=32491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/categories?post=32491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/tags?post=32491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}