{"id":29892,"date":"2019-11-20T07:32:43","date_gmt":"2019-11-20T06:32:43","guid":{"rendered":"https:\/\/wordpress-783423-2671269.cloudwaysapps.com\/?p=29892"},"modified":"2022-03-14T06:22:41","modified_gmt":"2022-03-14T05:22:41","slug":"20-november-2019-dermapharm-holding-se-treibt-unternehmenswachstum-im-dritten-quartal-2019-weiter-voran","status":"publish","type":"post","link":"https:\/\/dev.cometis.de\/de\/20-november-2019-dermapharm-holding-se-treibt-unternehmenswachstum-im-dritten-quartal-2019-weiter-voran\/","title":{"rendered":"20. November 2019 | Dermapharm Holding SE treibt Unternehmenswachstum im dritten Quartal 2019 weiter voran"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;section&#8220; _builder_version=&#8220;3.22&#8243; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220; da_disable_devices=&#8220;off|off|off&#8220;][et_pb_row padding_mobile=&#8220;off&#8220; column_padding_mobile=&#8220;on&#8220; admin_label=&#8220;Zeile&#8220; _builder_version=&#8220;3.25&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; custom_padding=&#8220;||0px|&#8220; make_fullwidth=&#8220;off&#8220; use_custom_width=&#8220;off&#8220; width_unit=&#8220;on&#8220; global_colors_info=&#8220;{}&#8220; column_structure=&#8220;1_2,1_2&#8243;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Schaltfl\u00e4che %22zur\u00fcck zum Archiv%22&#8243; _builder_version=&#8220;3.27.4&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; text_orientation=&#8220;left&#8220; use_border_color=&#8220;off&#8220; border_color=&#8220;#ffffff&#8220; border_style=&#8220;solid&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<style> .zur\u00fcckbutton:before {display: inline-block; font-family: \"ETmodules\"; content: \"\\4a\"; color: #00225f; margin-right: 7px;} .zur\u00fcckbutton:hover:before {display: inline-block; font-family: \"ETmodules\"; content: \"\\4a\"; color: #d85710; margin-right: 7px;}<\/style>\n<h1>Corporate News<\/h1>\n<p><a class=\"zur\u00fcckbutton\" href=\"https:\/\/dev.cometis.de\/veroeffentlichungsarchiv-dermapharm\">zum Archiv<\/a><br \/>\n[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/dev.cometis.de\/wp-content\/uploads\/2018\/08\/autodoc_Logo_Wei%C3%9F_2-7.png&#8220; align=&#8220;right&#8220; align_tablet=&#8220;center&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;Logo&#8220; _builder_version=&#8220;3.23&#8243; use_border_color=&#8220;off&#8220; border_color=&#8220;#ffffff&#8220; border_style=&#8220;solid&#8220; animation=&#8220;off&#8220; sticky=&#8220;off&#8220; always_center_on_mobile=&#8220;on&#8220; global_colors_info=&#8220;{}&#8220; align_phone=&#8220;center&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8220;row&#8220; _builder_version=&#8220;3.25&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Text&#8220; _builder_version=&#8220;3.27.4&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; text_orientation=&#8220;left&#8220; use_border_color=&#8220;off&#8220; border_color=&#8220;#ffffff&#8220; border_style=&#8220;solid&#8220; saved_tabs=&#8220;all&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h1>Dermapharm Holding SE treibt Unternehmenswachstum im dritten Quartal 2019 weiter voran<\/h1>\n<ul>\n<li>Konzernumsatz um 20,7% auf 517,6\u00a0Mio.\u00a0\u20ac gesteigert<\/li>\n<li>Bereinigtes Konzern-EBITDA von 133,1\u00a0Mio.\u00a0\u20ac um 25,1% deutlich \u00fcber Vorjahreswert; entsprechend bereinigte EBITDA-Marge auf 25,7% erh\u00f6ht<\/li>\n<li>Erfolgreiche Integration von Fitvia und Euromed sowie neues Logistikzentrum in Brehna verbessern Voraussetzungen f\u00fcr k\u00fcnftiges Wachstum<\/li>\n<li>Vorstand best\u00e4tigt Prognose f\u00fcr das Gesamtjahr 2019<\/li>\n<\/ul>\n<p><strong>Gr\u00fcnwald, 20. November 2019 \u2013 Die Dermapharm Holding SE (\u201eDermapharm\u201c), ein f\u00fchrender Hersteller von patentfreien Markenarzneimitteln f\u00fcr ausgew\u00e4hlte Therapiegebiete in Deutschland mit wachsender internationaler Pr\u00e4senz, ver\u00f6ffentlicht heute ihre Gesch\u00e4ftszahlen f\u00fcr die ersten neun Monate 2019. Das Unternehmen steigerte den Umsatz im Berichtszeitraum um 20,7% auf 517,6\u00a0Mio.\u00a0\u20ac (Vorjahreszeitraum: 429,0\u00a0Mio. \u20ac). Zugleich erh\u00f6hte sich das um Einmalkosten und R\u00fcckstellungen von insgesamt 8,5\u00a0Mio. \u20ac bereinigte Ergebnis vor Zinsen, Steuern und Abschreibungen (EBITDA) um 25,1% auf 133,1\u00a0Mio.\u00a0\u20ac (Vorjahreszeitraum: 106,4\u00a0Mio.\u00a0\u20ac). Die bereinigte EBITDA-Marge lag entsprechend bei 25,7% und damit 0,9\u00a0Prozentpunkte \u00fcber der Marge des Vorjahres. Das unbereinigte EBITDA betrug 124,6\u00a0Mio.\u00a0\u20ac, die unbereinigte EBITDA-Marge lag bei 24,1%.<\/strong><\/p>\n<p>Dr. Hans-Georg Feldmeier, Vorstandsvorsitzender der Dermapharm Holding SE, kommentiert: \u201eDie Zahlen der ersten neun Monate 2019 zeigen, dass unsere Wachstumsstrategie richtig ist. Die erfolgreich integrierten Konzerngesellschaften Strathmann und Trommsdorff bereichern unser Portfolio um attraktive Produkte und haben im Berichtszeitraum ma\u00dfgeblich zum organischen Wachstum beigetragen. Ein Beispiel ist das Muskelrelaxans-Pr\u00e4parat Myopridin\u00ae von Strathmann, das wir seit Jahresbeginn auch unter der Marke Myditin\u00ae \u00fcber Trommsdorff vertreiben und hervorragend im Markt angenommen wird. Die Integration der Euromed und der damit verbundene Aufbau des neuen Segments der \u201aPflanzlichen Extrakte\u2018 l\u00e4uft planm\u00e4\u00dfig.\u201c<\/p>\n<p>Um die Voraussetzungen f\u00fcr k\u00fcnftiges Wachstum weiter zu verbessern, hat Dermapharm zudem ihre Logistikkapazit\u00e4ten ausgebaut. \u201eWir sind stolz darauf, dass wir unser neues Logistikzentrum am Hauptproduktionsstandort Brehna im Laufe des Novembers planm\u00e4\u00dfig in Betrieb nehmen werden. Das neu errichtete Versandlager mit ca. 12.000 qm ist Voraussetzung f\u00fcr die st\u00e4ndige Verbesserung von Kundenn\u00e4he und Lieferperformance getreu unserer Strategie \u201eAlles unter einem Dach\u201c. Es schafft die Voraussetzungen f\u00fcr eine kosteng\u00fcnstige Logistik und Wachstum und ist ein Bekenntnis zum Produktionsstandort Deutschland\u201c, f\u00fchrt Dr. Feldmeier weiter aus.<\/p>\n<p>Den Umsatz im Segment \u201eMarkenarzneimittel und andere Gesundheitsprodukte\u201c konnte Dermapharm um 10,7% auf 276,2\u00a0Mio.\u00a0\u20ac (Vorjahreszeitraum: 249,5\u00a0Mio.\u00a0\u20ac) steigern. Somit erh\u00f6hte sich das um Einmalkosten im Zusammenhang mit dem Erwerb von Euromed und Fitvia in H\u00f6he von 3,1\u00a0Mio.\u00a0\u20ac, Beratungsleistungen im Zusammenhang mit weiteren Akquisitionsbem\u00fchungen in H\u00f6he von 0,2\u00a0Mio.\u00a0\u20ac sowie Restrukturierungskosten bei Bio-Di\u00e4t-Berlin und deren Tochtergesellschaft Kr\u00e4uter K\u00fchne in H\u00f6he von 1,6\u00a0Mio.\u00a0\u20ac bereinigte EBITDA des Segments um 11,5% auf 113,8\u00a0Mio.\u00a0\u20ac (Vorjahreszeitraum: 102,1\u00a0Mio.\u00a0\u20ac). Diese Steigerung basierte ma\u00dfgeblich auf der positiven Entwicklung des Rohertrags bei gleichzeitiger Senkung der Materialkosten-Ratio. Die um Einmalkosten im Zusammenhang mit den Akquisitionen von Euromed und Fitvia, Beratungsleistungen im Rahmen von weiteren Akquisitionsbem\u00fchungen sowie Restrukturierungskosten bei Bio-Di\u00e4t-Berlin bereinigte EBITDA-Marge des Segments lag mit 41,2% \u00fcber dem entsprechenden Vorjahreswert von 40,9%.<\/p>\n<p>Im Segment \u201eParallelimportgesch\u00e4ft\u201c stieg der Umsatz im Berichtszeitraum um 3,1% auf 185,1\u00a0Mio.\u00a0\u20ac (Vorjahreszeitraum: 179,5\u00a0Mio. \u20ac)\u00a0an. Dieser Anstieg resultierte im Wesentlichen aus einer grunds\u00e4tzlich stabilen Nachfrage nach parallelimportierten Originalpr\u00e4paraten und einer intakten Lieferf\u00e4higkeit der Dermapharm. Aufgrund einer zunehmenden Anzahl von Rabattausschreibungen der Krankenkassen f\u00fcr umsatzstarke Originator-Pr\u00e4parate, die kurz vor Patentablauf stehen, sank das EBITDA in diesem Segment um 7,7% auf 7,2\u00a0Mio.\u00a0\u20ac (Vorjahreszeitraum: 7,8\u00a0Mio.\u00a0\u20ac). Entsprechend lag die EBITDA-Marge des traditionell niedrigmargigen Segments mit 3,9% unter dem Vorjahreswert von 4,4%.<\/p>\n<p>Das neu geschaffene und erstmalig konsolidierte Segment \u201ePflanzliche Extrakte\u201c entwickelte sich entsprechend der Erwartungen. In diesem Bereich konnte Dermapharm durch die erworbene Euromed einen Umsatzbeitrag von 56,3\u00a0Mio.\u00a0\u20ac erwirtschaften. Das um Einmalkosten der Bestandsminderungen im Zusammenhang mit dem \u201eStep-up des Buchwertes\u201c der zum Kaufzeitpunkt vorhandenen Vorr\u00e4te in H\u00f6he von 3,6 Mio. bereinigte EBITDA des Segments betrug 16,2\u00a0Mio.\u00a0\u20ac. Dies entspricht einer EBITDA-Marge von 28,8%.<\/p>\n<p>Angesichts der erfolgreichen strategischen Ausrichtung im Segment \u201eMarkenarzneimittel und andere Gesundheitsprodukte\u201c, der konsequenten Umsetzung der Drei-S\u00e4ulen-Strategie sowie der Wachstumsperspektiven im neuen Segment \u201ePflanzliche Extrakte\u201c best\u00e4tigt der Vorstand seine Prognose f\u00fcr das Gesch\u00e4ftsjahr 2019. Der Vorstand geht somit f\u00fcr 2019 im Vergleich zum Vorjahr nach wie vor von einem weiteren Konzernwachstum aus. Dabei erwartet er weiterhin, dass der Konzernumsatz 14% bis 19% und das EBITDA 17% bis 22% \u00fcber dem des Gesch\u00e4ftsjahres 2018 liegen werden.<\/p>\n<p>Die vollst\u00e4ndige Q3-Mitteilung 2019 ist ab heute auf der Internetseite ir.dermapharm.de verf\u00fcgbar.<br \/>\n[\/et_pb_text][et_pb_text admin_label=&#8220;Schaltfl\u00e4che %22Beitrag als PDF%22&#8243; _builder_version=&#8220;3.27.4&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; text_orientation=&#8220;left&#8220; use_border_color=&#8220;off&#8220; border_color=&#8220;#ffffff&#8220; border_style=&#8220;solid&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<div class=\"leseprobe-archiv\"><a title=\"Beitrag als PDF\" href=\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2019\/11\/20191120_CN_Dermapharm_Q3_2019_Zahlen_DE.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Beitrag als PDF<\/a><\/div>\n<style> .leseprobe-archiv {color: #00225f !important; border-color: #00225f; position: relative; padding: 0.3em 1em; border: 1px solid; -webkit-border-radius: 3px; -moz-border-radius: 3px; border-radius: 3px; -webkit-transition: all 0.2s; -moz-transition: all 0.2s; transition: all 0.2s; padding:10px; width: 19%; text-align: center; margin-right: 10px; float:left;} .leseprobe-archiv:hover {background-color: #eee; border-color: #ffffff; cursor: pointer;}<\/style>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gr\u00fcnwald, 20. November 2019 \u2013 Die Dermapharm Holding SE (\u201eDermapharm\u201c), ein f\u00fchrender Hersteller von patentfreien Markenarzneimitteln f\u00fcr ausgew\u00e4hlte Therapiegebiete in Deutschland mit wachsender internationaler Pr\u00e4senz, ver\u00f6ffentlicht heute ihre Gesch\u00e4ftszahlen f\u00fcr die ersten neun Monate 2019. <\/p>\n","protected":false},"author":24813,"featured_media":54373,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[260,447],"tags":[497],"class_list":["post-29892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dermapharm-corporate-news","category-news","tag-497"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>20. November 2019 | Dermapharm Holding SE treibt Unternehmenswachstum im dritten Quartal 2019 weiter voran - cometis AG<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"20. November 2019 | Dermapharm Holding SE treibt Unternehmenswachstum im dritten Quartal 2019 weiter voran - cometis AG\" \/>\n<meta property=\"og:description\" content=\"Gr\u00fcnwald, 20. November 2019 \u2013 Die Dermapharm Holding SE (\u201eDermapharm\u201c), ein f\u00fchrender Hersteller von patentfreien Markenarzneimitteln f\u00fcr ausgew\u00e4hlte Therapiegebiete in Deutschland mit wachsender internationaler Pr\u00e4senz, ver\u00f6ffentlicht heute ihre Gesch\u00e4ftszahlen f\u00fcr die ersten neun Monate 2019.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.cometis.de\/de\/20-november-2019-dermapharm-holding-se-treibt-unternehmenswachstum-im-dritten-quartal-2019-weiter-voran\/\" \/>\n<meta property=\"og:site_name\" content=\"cometis AG\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-20T06:32:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-14T05:22:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Assistenz cometis AG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Assistenz cometis AG\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.cometis.de\/de\/20-november-2019-dermapharm-holding-se-treibt-unternehmenswachstum-im-dritten-quartal-2019-weiter-voran\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/20-november-2019-dermapharm-holding-se-treibt-unternehmenswachstum-im-dritten-quartal-2019-weiter-voran\/\"},\"author\":{\"name\":\"Assistenz cometis AG\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/0f6ec71e9167dd48a24950f3cc6b2003\"},\"headline\":\"20. November 2019 | Dermapharm Holding SE treibt Unternehmenswachstum im dritten Quartal 2019 weiter voran\",\"datePublished\":\"2019-11-20T06:32:43+00:00\",\"dateModified\":\"2022-03-14T05:22:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/20-november-2019-dermapharm-holding-se-treibt-unternehmenswachstum-im-dritten-quartal-2019-weiter-voran\/\"},\"wordCount\":1074,\"publisher\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/20-november-2019-dermapharm-holding-se-treibt-unternehmenswachstum-im-dritten-quartal-2019-weiter-voran\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg\",\"keywords\":[\"2019\"],\"articleSection\":[\"Dermapharm Corporate News\",\"News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.cometis.de\/de\/20-november-2019-dermapharm-holding-se-treibt-unternehmenswachstum-im-dritten-quartal-2019-weiter-voran\/\",\"url\":\"https:\/\/dev.cometis.de\/de\/20-november-2019-dermapharm-holding-se-treibt-unternehmenswachstum-im-dritten-quartal-2019-weiter-voran\/\",\"name\":\"20. November 2019 | Dermapharm Holding SE treibt Unternehmenswachstum im dritten Quartal 2019 weiter voran - cometis AG\",\"isPartOf\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/20-november-2019-dermapharm-holding-se-treibt-unternehmenswachstum-im-dritten-quartal-2019-weiter-voran\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/20-november-2019-dermapharm-holding-se-treibt-unternehmenswachstum-im-dritten-quartal-2019-weiter-voran\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg\",\"datePublished\":\"2019-11-20T06:32:43+00:00\",\"dateModified\":\"2022-03-14T05:22:41+00:00\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.cometis.de\/de\/20-november-2019-dermapharm-holding-se-treibt-unternehmenswachstum-im-dritten-quartal-2019-weiter-voran\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dev.cometis.de\/de\/20-november-2019-dermapharm-holding-se-treibt-unternehmenswachstum-im-dritten-quartal-2019-weiter-voran\/#primaryimage\",\"url\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg\",\"contentUrl\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg\",\"caption\":\"Icon Newsroom_news\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#website\",\"url\":\"https:\/\/dev.cometis.de\/de\/\",\"name\":\"cometis AG\",\"description\":\"Deutschlands f\u00fchrende Investor Relations Agentur\",\"publisher\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.cometis.de\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#organization\",\"name\":\"cometis AG\",\"alternateName\":\"Deutschlands f\u00fchrende Investor Relations Agentur\",\"url\":\"https:\/\/dev.cometis.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/01\/Cometis-Mobile-Logo-1.png\",\"contentUrl\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/01\/Cometis-Mobile-Logo-1.png\",\"width\":171,\"height\":31,\"caption\":\"cometis AG\"},\"image\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/0f6ec71e9167dd48a24950f3cc6b2003\",\"name\":\"Assistenz cometis AG\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d9db77bcddbfa0c99848135c21ae5b93?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d9db77bcddbfa0c99848135c21ae5b93?s=96&d=mm&r=g\",\"caption\":\"Assistenz cometis AG\"},\"url\":\"https:\/\/dev.cometis.de\/de\/author\/assistenz-cometis-ag\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"20. November 2019 | Dermapharm Holding SE treibt Unternehmenswachstum im dritten Quartal 2019 weiter voran - cometis AG","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"20. November 2019 | Dermapharm Holding SE treibt Unternehmenswachstum im dritten Quartal 2019 weiter voran - cometis AG","og_description":"Gr\u00fcnwald, 20. November 2019 \u2013 Die Dermapharm Holding SE (\u201eDermapharm\u201c), ein f\u00fchrender Hersteller von patentfreien Markenarzneimitteln f\u00fcr ausgew\u00e4hlte Therapiegebiete in Deutschland mit wachsender internationaler Pr\u00e4senz, ver\u00f6ffentlicht heute ihre Gesch\u00e4ftszahlen f\u00fcr die ersten neun Monate 2019.","og_url":"https:\/\/dev.cometis.de\/de\/20-november-2019-dermapharm-holding-se-treibt-unternehmenswachstum-im-dritten-quartal-2019-weiter-voran\/","og_site_name":"cometis AG","article_published_time":"2019-11-20T06:32:43+00:00","article_modified_time":"2022-03-14T05:22:41+00:00","og_image":[{"url":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg","width":1,"height":1,"type":"image\/png"}],"author":"Assistenz cometis AG","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Assistenz cometis AG","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.cometis.de\/de\/20-november-2019-dermapharm-holding-se-treibt-unternehmenswachstum-im-dritten-quartal-2019-weiter-voran\/#article","isPartOf":{"@id":"https:\/\/dev.cometis.de\/de\/20-november-2019-dermapharm-holding-se-treibt-unternehmenswachstum-im-dritten-quartal-2019-weiter-voran\/"},"author":{"name":"Assistenz cometis AG","@id":"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/0f6ec71e9167dd48a24950f3cc6b2003"},"headline":"20. November 2019 | Dermapharm Holding SE treibt Unternehmenswachstum im dritten Quartal 2019 weiter voran","datePublished":"2019-11-20T06:32:43+00:00","dateModified":"2022-03-14T05:22:41+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.cometis.de\/de\/20-november-2019-dermapharm-holding-se-treibt-unternehmenswachstum-im-dritten-quartal-2019-weiter-voran\/"},"wordCount":1074,"publisher":{"@id":"https:\/\/dev.cometis.de\/de\/#organization"},"image":{"@id":"https:\/\/dev.cometis.de\/de\/20-november-2019-dermapharm-holding-se-treibt-unternehmenswachstum-im-dritten-quartal-2019-weiter-voran\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg","keywords":["2019"],"articleSection":["Dermapharm Corporate News","News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/dev.cometis.de\/de\/20-november-2019-dermapharm-holding-se-treibt-unternehmenswachstum-im-dritten-quartal-2019-weiter-voran\/","url":"https:\/\/dev.cometis.de\/de\/20-november-2019-dermapharm-holding-se-treibt-unternehmenswachstum-im-dritten-quartal-2019-weiter-voran\/","name":"20. November 2019 | Dermapharm Holding SE treibt Unternehmenswachstum im dritten Quartal 2019 weiter voran - cometis AG","isPartOf":{"@id":"https:\/\/dev.cometis.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.cometis.de\/de\/20-november-2019-dermapharm-holding-se-treibt-unternehmenswachstum-im-dritten-quartal-2019-weiter-voran\/#primaryimage"},"image":{"@id":"https:\/\/dev.cometis.de\/de\/20-november-2019-dermapharm-holding-se-treibt-unternehmenswachstum-im-dritten-quartal-2019-weiter-voran\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg","datePublished":"2019-11-20T06:32:43+00:00","dateModified":"2022-03-14T05:22:41+00:00","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.cometis.de\/de\/20-november-2019-dermapharm-holding-se-treibt-unternehmenswachstum-im-dritten-quartal-2019-weiter-voran\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dev.cometis.de\/de\/20-november-2019-dermapharm-holding-se-treibt-unternehmenswachstum-im-dritten-quartal-2019-weiter-voran\/#primaryimage","url":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg","contentUrl":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg","caption":"Icon Newsroom_news"},{"@type":"WebSite","@id":"https:\/\/dev.cometis.de\/de\/#website","url":"https:\/\/dev.cometis.de\/de\/","name":"cometis AG","description":"Deutschlands f\u00fchrende Investor Relations Agentur","publisher":{"@id":"https:\/\/dev.cometis.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.cometis.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dev.cometis.de\/de\/#organization","name":"cometis AG","alternateName":"Deutschlands f\u00fchrende Investor Relations Agentur","url":"https:\/\/dev.cometis.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dev.cometis.de\/de\/#\/schema\/logo\/image\/","url":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/01\/Cometis-Mobile-Logo-1.png","contentUrl":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/01\/Cometis-Mobile-Logo-1.png","width":171,"height":31,"caption":"cometis AG"},"image":{"@id":"https:\/\/dev.cometis.de\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/0f6ec71e9167dd48a24950f3cc6b2003","name":"Assistenz cometis AG","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d9db77bcddbfa0c99848135c21ae5b93?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d9db77bcddbfa0c99848135c21ae5b93?s=96&d=mm&r=g","caption":"Assistenz cometis AG"},"url":"https:\/\/dev.cometis.de\/de\/author\/assistenz-cometis-ag\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/posts\/29892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/users\/24813"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/comments?post=29892"}],"version-history":[{"count":2,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/posts\/29892\/revisions"}],"predecessor-version":[{"id":56518,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/posts\/29892\/revisions\/56518"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/media\/54373"}],"wp:attachment":[{"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/media?parent=29892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/categories?post=29892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/tags?post=29892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}