{"id":27675,"date":"2019-07-30T09:00:09","date_gmt":"2019-07-30T07:00:09","guid":{"rendered":"https:\/\/wordpress-783423-2671269.cloudwaysapps.com\/?p=27675"},"modified":"2022-03-10T07:36:52","modified_gmt":"2022-03-10T06:36:52","slug":"der-untergang-des-aktien-researchs-eroeffnet-neue-chancen-fuer-den-boersennotierten-mittelstand","status":"publish","type":"post","link":"https:\/\/dev.cometis.de\/de\/der-untergang-des-aktien-researchs-eroeffnet-neue-chancen-fuer-den-boersennotierten-mittelstand\/","title":{"rendered":"Der \u201eUntergang des Aktien-Researchs\u201c\u2026 er\u00f6ffnet neue Chancen f\u00fcr den b\u00f6rsennotierten Mittelstand"},"content":{"rendered":"<p>[et_pb_section admin_label=&#8220;Sektion&#8220; global_module=&#8220;2286&#8243; fullwidth=&#8220;on&#8220; specialty=&#8220;off&#8220; transparent_background=&#8220;off&#8220; allow_player_pause=&#8220;off&#8220; inner_shadow=&#8220;off&#8220; parallax=&#8220;off&#8220; parallax_method=&#8220;off&#8220; padding_mobile=&#8220;off&#8220; make_fullwidth=&#8220;off&#8220; use_custom_width=&#8220;off&#8220; width_unit=&#8220;on&#8220; make_equal=&#8220;off&#8220; use_custom_gutter=&#8220;off&#8220; background_color=&#8220;#ffffff&#8220;][\/et_pb_section][et_pb_section admin_label=&#8220;section&#8220;][et_pb_row admin_label=&#8220;row&#8220;][et_pb_column type=&#8220;1_3&#8243;][et_pb_sidebar admin_label=&#8220;Seitenleiste&#8220; orientation=&#8220;left&#8220; area=&#8220;et_pb_widget_area_7&#8243; background_layout=&#8220;light&#8220; remove_border=&#8220;off&#8220;]<br \/>\n[\/et_pb_sidebar][et_pb_text admin_label=&#8220;M. Diegelmann CTA&#8220; global_module=&#8220;2526&#8243; saved_tabs=&#8220;all&#8220; background_layout=&#8220;light&#8220; text_orientation=&#8220;left&#8220; disabled=&#8220;off&#8220; disabled_on=&#8220;off|off|off&#8220; text_line_height=&#8220;2.1em&#8220; use_border_color=&#8220;off&#8220; border_color=&#8220;#ffffff&#8220; border_style=&#8220;solid&#8220; module_class=&#8220;shorter-field&#8220;]<\/p>\n<h3><span style=\"color: #00225f;\">Ihr Ansprechpartner<\/span><\/h3>\n<div class=\"sidebar-cta\">\n<div class=\"sidebar-cta-img\">\n<div class=\"et_pb_team_member_image et-waypoint et_pb_animation_off et-animated\"><img decoding=\"async\" src=\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2016\/10\/Michael-Diegelmann-cometis-ag.jpeg\" alt=\"Michael Diegelmann\" \/><\/div>\n<\/div>\n<div class=\"sidebar-cta-info\">\n<div class=\"et_pb_team_member_description\">\n<h6>Michael Diegelmann<\/h6>\n<div><a title=\"Rufen Sie an!\" href=\"tel:+49 611 20 58 55 18\"><span class=\"sidebar-phone-link\">+49 611 20 58 55 18<\/span><br \/>\n<\/a><a title=\"Schreiben Sie eine Mail!\" href=\"mailto:diegelmann@dev.cometis.de\"><span class=\"sidebar-mail-link\">diegelmann@dev.cometis.de<\/span><\/a><\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_contact_form admin_label=&#8220;Kontaktformular Diegelmann&#8220; saved_tabs=&#8220;all&#8220; captcha=&#8220;off&#8220; email=&#8220;weiterleitung.diegelmann@gmail.com&#8220; title=&#8220;Kontaktieren Sie uns:&#8220; custom_message=&#8220;Name: %%Name%%<br \/>\nE-Mail: %%Email%%<br \/>\nAnfrage: %%Message%%&#8220; use_redirect=&#8220;off&#8220; success_message=&#8220;Vielen Dank f\u00fcr Ihre Nachricht!&#8220; input_border_radius=&#8220;0&#8243; form_field_font_size=&#8220;16&#8243; form_field_line_height=&#8220;1.5em&#8220; use_border_color=&#8220;off&#8220; border_color=&#8220;#ffffff&#8220; border_style=&#8220;solid&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;16&#8243; button_border_width=&#8220;1&#8243; button_letter_spacing=&#8220;0&#8243; button_use_icon=&#8220;default&#8220; button_icon=&#8220;%%20%%&#8220; button_icon_color=&#8220;#d85710&#8243; button_icon_placement=&#8220;right&#8220; button_on_hover=&#8220;on&#8220; button_letter_spacing_hover=&#8220;0&#8243;] [et_pb_contact_field field_title=&#8220;Name&#8220; field_type=&#8220;input&#8220; field_id=&#8220;Name&#8220; required_mark=&#8220;on&#8220; fullwidth_field=&#8220;on&#8220; form_field_font_select=&#8220;default&#8220; form_field_font=&#8220;||||&#8220; use_border_color=&#8220;off&#8220; border_style=&#8220;solid&#8220;]<br \/>\n[\/et_pb_contact_field][et_pb_contact_field field_title=&#8220;E-Mail-Adresse&#8220; field_type=&#8220;email&#8220; field_id=&#8220;Email&#8220; required_mark=&#8220;on&#8220; fullwidth_field=&#8220;on&#8220; form_field_font_select=&#8220;default&#8220; form_field_font=&#8220;||||&#8220; use_border_color=&#8220;off&#8220; border_style=&#8220;solid&#8220;]<br \/>\n[\/et_pb_contact_field][et_pb_contact_field field_title=&#8220;Nachricht&#8220; field_type=&#8220;text&#8220; field_id=&#8220;Message&#8220; required_mark=&#8220;on&#8220; fullwidth_field=&#8220;on&#8220; form_field_font_select=&#8220;default&#8220; form_field_font=&#8220;||||&#8220; use_border_color=&#8220;off&#8220; border_style=&#8220;solid&#8220;]<br \/>\n[\/et_pb_contact_field] [\/et_pb_contact_form][\/et_pb_column][et_pb_column type=&#8220;2_3&#8243;][et_pb_post_title admin_label=&#8220;Posttitel&#8220; global_module=&#8220;2295&#8243; saved_tabs=&#8220;all&#8220; title=&#8220;on&#8220; meta=&#8220;on&#8220; author=&#8220;off&#8220; date=&#8220;on&#8220; date_format=&#8220;j M, Y&#8220; categories=&#8220;on&#8220; comments=&#8220;on&#8220; featured_image=&#8220;on&#8220; featured_placement=&#8220;below&#8220; parallax_effect=&#8220;on&#8220; parallax_method=&#8220;on&#8220; text_orientation=&#8220;left&#8220; text_color=&#8220;dark&#8220; text_background=&#8220;off&#8220; text_bg_color=&#8220;rgba(255,255,255,0.9)&#8220; module_bg_color=&#8220;rgba(255,255,255,0)&#8220; title_all_caps=&#8220;off&#8220; use_border_color=&#8220;off&#8220; border_color=&#8220;#ffffff&#8220; border_style=&#8220;solid&#8220;]<br \/>\n[\/et_pb_post_title][et_pb_text admin_label=&#8220;Text&#8220; background_layout=&#8220;light&#8220; text_orientation=&#8220;left&#8220; use_border_color=&#8220;off&#8220; border_color=&#8220;#ffffff&#8220; border_style=&#8220;solid&#8220;]<\/p>\n<p><strong>Researchberichte werden seltener. Die aktuellen rechtlichen Vorgaben der EU-Richtlinie MiFID II wirken nochmals trendverst\u00e4rkend. Kleinere und mittelgro\u00dfe Aktiengesellschaften verschwinden aus den Coverlisten der Researchabteilungen. Deren Papiere werden seltener gehandelt und die Banken k\u00f6nnen weniger Provisionen verdienen. Zugleich bleiben diese Werte jedoch attraktiv f\u00fcr Investoren. Der Mittelstand ist innovativ und w\u00e4chst schneller als Gro\u00dfunternehmen. Es entsteht eine L\u00fccke zwischen den ungebrochen attraktiven Investitionsm\u00f6glichkeiten und dem geringen unabh\u00e4ngigen Researchangebot. Zugleich findet bezahltes Research keine Akzeptanz bei Investoren. Welche Chancen ergeben sich daraus f\u00fcr b\u00f6rsennotierte Mittelst\u00e4ndler?<\/strong><\/p>\n<p>Seit der Jahrtausendwende d\u00fcnnen viele Banken ihre zentralen Abteilungen aus. Die Finanzkrise hat diesen Trend verst\u00e4rkt. Das Ergebnis: Laut DVFA ging in den letzten 20 Jahren die Zahl der Aktienanalysten in Deutschland um rund ein Drittel auf rund 250 zur\u00fcck. Die Regulierung durch MiFID II d\u00fcrfte die Schrumpfung nochmals beschleunigen. Die EU-Richtlinie schreibt vor, dass Investoren direkt f\u00fcr das erhaltene Research zahlen. Zuvor wurde das Research \u00fcber Handelsauftr\u00e4ge subventioniert. Seither muss das Research separat bestellt \u2013 und auch bezahlt \u2013 werden. Offenbar gen\u00fcgt die Qualit\u00e4t vieler Studien nicht den Anforderungen der Investoren. Andernfalls w\u00e4ren sie gerne bereit zu zahlen. Auch von den Emittenten selbst bezahltes Research d\u00fcrfte wenig daran \u00e4ndern. Zum einen wird kaum ein Emittent kritische Studien zu seinem Unternehmen verg\u00fcten. Zum anderen werden aber gekaufte Studien von den Investoren nicht akzeptiert. Es stellt sich die Frage, wie Anbieter des von Emittenten bezahlter Studien \u00fcberhaupt (seri\u00f6s) Geld verdienen k\u00f6nnen. Folglich d\u00fcrften aufgrund der geringen Zahlungsbereitschaft der Investoren und der Emittenten viele Banken abermals die Axt an die (Kosten)Stellen legen.<br \/>\nMit der sinkenden Zahl von Analysten schrumpft auch die Zahl der analysierten Unternehmen. \u00dcber kleinere und mittlere Unternehmen wird immer seltener berichtet. Und manche Firmen werden gar nicht mehr beobachtet. Fehlt die neutrale Beurteilung der Qualit\u00e4t mancher Aktien, besteht die Gefahr, dass viele Investoren ganz die Finger von diesen Unternehmen lassen. Geht also im Small und Mid Cap-Bereich das Licht aus? Das muss keineswegs zwangsl\u00e4ufig so sein &#8211; wie die Entwicklung des Medienwelt zeigt.<\/p>\n<p><strong>Parallelen zur Transformation der Medienwelt<\/strong><br \/>\nDer Siegeszug des Internets geht mit einem Bedeutungsverlust klassischer Printmedien einher. Gerade j\u00fcngere Leute greifen kaum noch zur Tageszeitung. Das spiegelt sich auch in den Redaktionen wider. Seit der Jahrtausendwende ist die Zahl der bei Tageszeitungen und Zeitschriften besch\u00e4ftigten Journalisten von rund 30.000 auf rund 20.000 zur\u00fcckgegangen. Der Aderlass von rund einem Drittel ist eine auff\u00e4llige Parallele zur r\u00fcckl\u00e4ufigen Zahl von Finanzanalysten. Zur\u00fcck bleibt aber keineswegs ein Vakuum. Andere Medien f\u00fcllen die L\u00fccken. Internetmedien gewinnen an Bedeutung. So hat Twitter mit dem flei\u00dfig zwitschernden US-Pr\u00e4sidenten eine zuvor kaum f\u00fcr m\u00f6glich gehaltene Bedeutung erhalten. Und auch YouTube pr\u00e4gt inzwischen die politische Diskussion \u2013 wie dies zuletzt die CDU schmerzlich erfahren musste. Das Berufsbild des \u201eYoutubers\u201c oder \u201eInfluencers\u201c war vor wenigen Jahren noch unbekannt. Heute sind Influencer am Meinungsmarkt etabliert und gewinnen weiter an Bedeutung. Bereits jetzt tummeln sich hierzulande rund 30.000 Influenzer im Netz. Dabei vereinigen drei Prozent der Youtuber 85 Prozent aller Views auf sich \u2013 und agieren umso durchschlagender. Wer sich weiterhin Geh\u00f6r verschaffen will, muss die neuen Kan\u00e4le ad\u00e4quat bedienen.<br \/>\nWie k\u00f6nnte nun die Zukunft der Analystenglide aussehen? Viele werden vorausssichtlich in die Bereiche Corporate Finance und Investor Relations wechseln oder in den Finanzbereich von Unternehmen gehen. Die Besten werden vermutlich vom Buyside-Reseach gro\u00dfer Verm\u00f6gensverwalter aufgesogen. Einige unternehmerisch denkende Analysten werden sich als Einzelk\u00e4mpfer versuchen oder zu Miniteams formieren und \u00fcber das Internet neue Kundengruppen erschlie\u00dfen. Kleine Einheiten agieren schneller als herk\u00f6mmliche Researchfabriken. Sie k\u00f6nnen ihre Kommunikation individuell auf spezielle Zielgruppen zuschneiden. In einem n\u00e4chsten Schritt k\u00f6nnten sich die Einzelk\u00e4mpfer zu schlagkr\u00e4ftigeren Netzwerken, Brands zusammenfinden. Die breit aufgestellten Anwaltskanzleien sind eine entsprechende Blaupause.<\/p>\n<p>Solange es lohnende Investitionsm\u00f6glichkeiten gibt, wird das Angebot sich seine Nachfrage schaffen. Investoren d\u00fcrften auch bereit sein f\u00fcr gute Informationen zu zahlen. Aber nur wenn sie einen Mehrwert erkennen. Hier entsteht eine Chance f\u00fcr gute Aktienanalysten. Dann sollten sie allerdings nicht nur Unternehmensmeldungen umformulieren, sondern m\u00fcssen einen echten Mehrwert liefern. Sektorspezialisten werden vermutlich europaweit oder weltweit agieren. Wie herk\u00f6mmliche Branchen ihre Produkte vom Automobil bis zum Smartphone international vertreiben, d\u00fcrften auch Researcher global ihre Kunden gewinnen.<\/p>\n<p><strong>Schlussfolgerungen f\u00fcr die Investor Relations Arbeit<\/strong><br \/>\nDas (potenzielle) Interesse der Investoren bleibt unver\u00e4ndert. Das Research wird aber weniger. Unternehmen m\u00fcssen deshalb zuk\u00fcnftig ihre B\u00f6rsennotiz selbst steuern. Mittelst\u00e4ndische Unternehmen sollten zuk\u00fcnftig differenzierter kommunizieren. \u00dcber die Pflichtberichterstattung hinaus werden weitere zielgruppengerechte Informationen zum Trumpf. IR-Factbooks k\u00f6nnen Unternehmensstudien ersetzen. Zudem erweitern brokerunabh\u00e4ngige Roadshows und Capital Market Days die Aufgaben der IR-Manager. So l\u00e4sst sich das Interesse internationaler Anleger wecken. Mit Videobotschaften lassen sich auch private Investoren gewinnen. Wie in der Medienwelt d\u00fcrfte damit zuk\u00fcnftig in der Investor Relations-Arbeit die direkte Kommunikation &#8211; also ohne Broker oder andere Mittler &#8211; stark an Bedeutung gewinnen. Das gilt sowohl f\u00fcr digitale als auch die klassische, pers\u00f6nliche Kommunikation.<\/p>\n<p>[\/et_pb_text][et_pb_button admin_label=&#8220;Taste&#8220; global_module=&#8220;9119&#8243; button_url=&#8220;https:\/\/dev.cometis.de\/cometis-ag\/news&#8220; url_new_window=&#8220;off&#8220; button_text=&#8220;Zur\u00fcck zum News-Bereich&#8220; button_alignment=&#8220;right&#8220; background_layout=&#8220;dark&#8220; custom_button=&#8220;on&#8220; button_bg_color=&#8220;#d85710&#8243; button_letter_spacing=&#8220;0&#8243; button_use_icon=&#8220;default&#8220; button_icon_placement=&#8220;right&#8220; button_on_hover=&#8220;on&#8220; button_letter_spacing_hover=&#8220;0&#8243; button_text_size=&#8220;14&#8243; saved_tabs=&#8220;all&#8220;]<br \/>\n[\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ihr Ansprechpartner Michael Diegelmann +49 611 20 58 55 18 diegelmann@dev.cometis.de &nbsp; Researchberichte werden seltener. Die aktuellen rechtlichen Vorgaben der EU-Richtlinie MiFID II wirken nochmals trendverst\u00e4rkend. Kleinere und mittelgro\u00dfe Aktiengesellschaften verschwinden aus den Coverlisten der Researchabteilungen. Deren Papiere werden seltener gehandelt und die Banken k\u00f6nnen weniger Provisionen verdienen. Zugleich bleiben diese Werte jedoch attraktiv f\u00fcr [&hellip;]<\/p>\n","protected":false},"author":24813,"featured_media":54373,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[447,88],"tags":[497],"class_list":["post-27675","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-pressemitteilung","tag-497"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Der \u201eUntergang des Aktien-Researchs\u201c\u2026 er\u00f6ffnet neue Chancen f\u00fcr den b\u00f6rsennotierten Mittelstand - cometis AG<\/title>\n<meta name=\"description\" content=\"Researchberichte werden seltener. Die aktuellen rechtlichen Vorgaben der EU-Richtlinie MiFID II wirken nochmals trendverst\u00e4rkend. Kleinere und mittelgro\u00dfe Aktiengesellschaften verschwinden aus den Coverlisten der Researchabteilungen.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der \u201eUntergang des Aktien-Researchs\u201c\u2026 er\u00f6ffnet neue Chancen f\u00fcr den b\u00f6rsennotierten Mittelstand - cometis AG\" \/>\n<meta property=\"og:description\" content=\"Researchberichte werden seltener. Die aktuellen rechtlichen Vorgaben der EU-Richtlinie MiFID II wirken nochmals trendverst\u00e4rkend. Kleinere und mittelgro\u00dfe Aktiengesellschaften verschwinden aus den Coverlisten der Researchabteilungen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.cometis.de\/de\/der-untergang-des-aktien-researchs-eroeffnet-neue-chancen-fuer-den-boersennotierten-mittelstand\/\" \/>\n<meta property=\"og:site_name\" content=\"cometis AG\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-30T07:00:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-10T06:36:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Assistenz cometis AG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Assistenz cometis AG\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.cometis.de\/de\/der-untergang-des-aktien-researchs-eroeffnet-neue-chancen-fuer-den-boersennotierten-mittelstand\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/der-untergang-des-aktien-researchs-eroeffnet-neue-chancen-fuer-den-boersennotierten-mittelstand\/\"},\"author\":{\"name\":\"Assistenz cometis AG\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/0f6ec71e9167dd48a24950f3cc6b2003\"},\"headline\":\"Der \u201eUntergang des Aktien-Researchs\u201c\u2026 er\u00f6ffnet neue Chancen f\u00fcr den b\u00f6rsennotierten Mittelstand\",\"datePublished\":\"2019-07-30T07:00:09+00:00\",\"dateModified\":\"2022-03-10T06:36:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/der-untergang-des-aktien-researchs-eroeffnet-neue-chancen-fuer-den-boersennotierten-mittelstand\/\"},\"wordCount\":1411,\"publisher\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/der-untergang-des-aktien-researchs-eroeffnet-neue-chancen-fuer-den-boersennotierten-mittelstand\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg\",\"keywords\":[\"2019\"],\"articleSection\":[\"News\",\"Pressemitteilung\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.cometis.de\/de\/der-untergang-des-aktien-researchs-eroeffnet-neue-chancen-fuer-den-boersennotierten-mittelstand\/\",\"url\":\"https:\/\/dev.cometis.de\/de\/der-untergang-des-aktien-researchs-eroeffnet-neue-chancen-fuer-den-boersennotierten-mittelstand\/\",\"name\":\"Der \u201eUntergang des Aktien-Researchs\u201c\u2026 er\u00f6ffnet neue Chancen f\u00fcr den b\u00f6rsennotierten Mittelstand - cometis AG\",\"isPartOf\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/der-untergang-des-aktien-researchs-eroeffnet-neue-chancen-fuer-den-boersennotierten-mittelstand\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/der-untergang-des-aktien-researchs-eroeffnet-neue-chancen-fuer-den-boersennotierten-mittelstand\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg\",\"datePublished\":\"2019-07-30T07:00:09+00:00\",\"dateModified\":\"2022-03-10T06:36:52+00:00\",\"description\":\"Researchberichte werden seltener. Die aktuellen rechtlichen Vorgaben der EU-Richtlinie MiFID II wirken nochmals trendverst\u00e4rkend. Kleinere und mittelgro\u00dfe Aktiengesellschaften verschwinden aus den Coverlisten der Researchabteilungen.\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.cometis.de\/de\/der-untergang-des-aktien-researchs-eroeffnet-neue-chancen-fuer-den-boersennotierten-mittelstand\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dev.cometis.de\/de\/der-untergang-des-aktien-researchs-eroeffnet-neue-chancen-fuer-den-boersennotierten-mittelstand\/#primaryimage\",\"url\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg\",\"contentUrl\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg\",\"caption\":\"Icon Newsroom_news\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#website\",\"url\":\"https:\/\/dev.cometis.de\/de\/\",\"name\":\"cometis AG\",\"description\":\"Deutschlands f\u00fchrende Investor Relations Agentur\",\"publisher\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.cometis.de\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#organization\",\"name\":\"cometis AG\",\"alternateName\":\"Deutschlands f\u00fchrende Investor Relations Agentur\",\"url\":\"https:\/\/dev.cometis.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/01\/Cometis-Mobile-Logo-1.png\",\"contentUrl\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/01\/Cometis-Mobile-Logo-1.png\",\"width\":171,\"height\":31,\"caption\":\"cometis AG\"},\"image\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/0f6ec71e9167dd48a24950f3cc6b2003\",\"name\":\"Assistenz cometis AG\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d9db77bcddbfa0c99848135c21ae5b93?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d9db77bcddbfa0c99848135c21ae5b93?s=96&d=mm&r=g\",\"caption\":\"Assistenz cometis AG\"},\"url\":\"https:\/\/dev.cometis.de\/de\/author\/assistenz-cometis-ag\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Der \u201eUntergang des Aktien-Researchs\u201c\u2026 er\u00f6ffnet neue Chancen f\u00fcr den b\u00f6rsennotierten Mittelstand - cometis AG","description":"Researchberichte werden seltener. Die aktuellen rechtlichen Vorgaben der EU-Richtlinie MiFID II wirken nochmals trendverst\u00e4rkend. Kleinere und mittelgro\u00dfe Aktiengesellschaften verschwinden aus den Coverlisten der Researchabteilungen.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Der \u201eUntergang des Aktien-Researchs\u201c\u2026 er\u00f6ffnet neue Chancen f\u00fcr den b\u00f6rsennotierten Mittelstand - cometis AG","og_description":"Researchberichte werden seltener. Die aktuellen rechtlichen Vorgaben der EU-Richtlinie MiFID II wirken nochmals trendverst\u00e4rkend. Kleinere und mittelgro\u00dfe Aktiengesellschaften verschwinden aus den Coverlisten der Researchabteilungen.","og_url":"https:\/\/dev.cometis.de\/de\/der-untergang-des-aktien-researchs-eroeffnet-neue-chancen-fuer-den-boersennotierten-mittelstand\/","og_site_name":"cometis AG","article_published_time":"2019-07-30T07:00:09+00:00","article_modified_time":"2022-03-10T06:36:52+00:00","og_image":[{"url":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg","width":1,"height":1,"type":"image\/png"}],"author":"Assistenz cometis AG","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Assistenz cometis AG","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.cometis.de\/de\/der-untergang-des-aktien-researchs-eroeffnet-neue-chancen-fuer-den-boersennotierten-mittelstand\/#article","isPartOf":{"@id":"https:\/\/dev.cometis.de\/de\/der-untergang-des-aktien-researchs-eroeffnet-neue-chancen-fuer-den-boersennotierten-mittelstand\/"},"author":{"name":"Assistenz cometis AG","@id":"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/0f6ec71e9167dd48a24950f3cc6b2003"},"headline":"Der \u201eUntergang des Aktien-Researchs\u201c\u2026 er\u00f6ffnet neue Chancen f\u00fcr den b\u00f6rsennotierten Mittelstand","datePublished":"2019-07-30T07:00:09+00:00","dateModified":"2022-03-10T06:36:52+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.cometis.de\/de\/der-untergang-des-aktien-researchs-eroeffnet-neue-chancen-fuer-den-boersennotierten-mittelstand\/"},"wordCount":1411,"publisher":{"@id":"https:\/\/dev.cometis.de\/de\/#organization"},"image":{"@id":"https:\/\/dev.cometis.de\/de\/der-untergang-des-aktien-researchs-eroeffnet-neue-chancen-fuer-den-boersennotierten-mittelstand\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg","keywords":["2019"],"articleSection":["News","Pressemitteilung"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/dev.cometis.de\/de\/der-untergang-des-aktien-researchs-eroeffnet-neue-chancen-fuer-den-boersennotierten-mittelstand\/","url":"https:\/\/dev.cometis.de\/de\/der-untergang-des-aktien-researchs-eroeffnet-neue-chancen-fuer-den-boersennotierten-mittelstand\/","name":"Der \u201eUntergang des Aktien-Researchs\u201c\u2026 er\u00f6ffnet neue Chancen f\u00fcr den b\u00f6rsennotierten Mittelstand - cometis AG","isPartOf":{"@id":"https:\/\/dev.cometis.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.cometis.de\/de\/der-untergang-des-aktien-researchs-eroeffnet-neue-chancen-fuer-den-boersennotierten-mittelstand\/#primaryimage"},"image":{"@id":"https:\/\/dev.cometis.de\/de\/der-untergang-des-aktien-researchs-eroeffnet-neue-chancen-fuer-den-boersennotierten-mittelstand\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg","datePublished":"2019-07-30T07:00:09+00:00","dateModified":"2022-03-10T06:36:52+00:00","description":"Researchberichte werden seltener. Die aktuellen rechtlichen Vorgaben der EU-Richtlinie MiFID II wirken nochmals trendverst\u00e4rkend. Kleinere und mittelgro\u00dfe Aktiengesellschaften verschwinden aus den Coverlisten der Researchabteilungen.","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.cometis.de\/de\/der-untergang-des-aktien-researchs-eroeffnet-neue-chancen-fuer-den-boersennotierten-mittelstand\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dev.cometis.de\/de\/der-untergang-des-aktien-researchs-eroeffnet-neue-chancen-fuer-den-boersennotierten-mittelstand\/#primaryimage","url":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg","contentUrl":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg","caption":"Icon Newsroom_news"},{"@type":"WebSite","@id":"https:\/\/dev.cometis.de\/de\/#website","url":"https:\/\/dev.cometis.de\/de\/","name":"cometis AG","description":"Deutschlands f\u00fchrende Investor Relations Agentur","publisher":{"@id":"https:\/\/dev.cometis.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.cometis.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dev.cometis.de\/de\/#organization","name":"cometis AG","alternateName":"Deutschlands f\u00fchrende Investor Relations Agentur","url":"https:\/\/dev.cometis.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dev.cometis.de\/de\/#\/schema\/logo\/image\/","url":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/01\/Cometis-Mobile-Logo-1.png","contentUrl":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/01\/Cometis-Mobile-Logo-1.png","width":171,"height":31,"caption":"cometis AG"},"image":{"@id":"https:\/\/dev.cometis.de\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/0f6ec71e9167dd48a24950f3cc6b2003","name":"Assistenz cometis AG","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d9db77bcddbfa0c99848135c21ae5b93?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d9db77bcddbfa0c99848135c21ae5b93?s=96&d=mm&r=g","caption":"Assistenz cometis AG"},"url":"https:\/\/dev.cometis.de\/de\/author\/assistenz-cometis-ag\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/posts\/27675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/users\/24813"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/comments?post=27675"}],"version-history":[{"count":0,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/posts\/27675\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/media\/54373"}],"wp:attachment":[{"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/media?parent=27675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/categories?post=27675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/tags?post=27675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}