{"id":22418,"date":"2018-12-18T07:45:17","date_gmt":"2018-12-18T06:45:17","guid":{"rendered":"https:\/\/wordpress-783423-2671269.cloudwaysapps.com\/?p=22418"},"modified":"2022-03-14T05:28:23","modified_gmt":"2022-03-14T04:28:23","slug":"18-dezember-2018-creditshelf-startet-zusammen-mit-crosslend-die-erste-digitale-verbriefung-von-mittelstandskrediten","status":"publish","type":"post","link":"https:\/\/dev.cometis.de\/de\/18-dezember-2018-creditshelf-startet-zusammen-mit-crosslend-die-erste-digitale-verbriefung-von-mittelstandskrediten\/","title":{"rendered":"18. Dezember 2018 | creditshelf startet zusammen mit CrossLend die erste digitale Verbriefung von Mittelstandskrediten"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;section&#8220; _builder_version=&#8220;3.22&#8243; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220; da_disable_devices=&#8220;off|off|off&#8220;][et_pb_row padding_mobile=&#8220;off&#8220; column_padding_mobile=&#8220;on&#8220; admin_label=&#8220;Zeile&#8220; _builder_version=&#8220;3.25&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; custom_padding=&#8220;||0px|&#8220; make_fullwidth=&#8220;off&#8220; use_custom_width=&#8220;off&#8220; width_unit=&#8220;on&#8220; global_colors_info=&#8220;{}&#8220; column_structure=&#8220;1_2,1_2&#8243;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Schaltfl\u00e4che %22zur\u00fcck zum Archiv%22&#8243; _builder_version=&#8220;3.27.4&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; text_orientation=&#8220;left&#8220; use_border_color=&#8220;off&#8220; border_color=&#8220;#ffffff&#8220; border_style=&#8220;solid&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<style> .zur\u00fcckbutton:before {display: inline-block; font-family: \"ETmodules\"; content: \"\\4a\"; color: #00225f; margin-right: 7px;} .zur\u00fcckbutton:hover:before {display: inline-block; font-family: \"ETmodules\"; content: \"\\4a\"; color: #d85710; margin-right: 7px;}<\/style>\n<h1>Corporate News<\/h1>\n<p><a class=\"zur\u00fcckbutton\" href=\"https:\/\/dev.cometis.de\/veroeffentlichungsarchiv-creditshelf\">zum Archiv<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/dev.cometis.de\/wp-content\/uploads\/2018\/08\/CS_Logo_CMYK_Zeichenfl%C3%A4che-1.png&#8220; align=&#8220;right&#8220; align_tablet=&#8220;center&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;Logo&#8220; _builder_version=&#8220;3.23&#8243; use_border_color=&#8220;off&#8220; border_color=&#8220;#ffffff&#8220; border_style=&#8220;solid&#8220; animation=&#8220;off&#8220; sticky=&#8220;off&#8220; always_center_on_mobile=&#8220;on&#8220; global_colors_info=&#8220;{}&#8220; align_phone=&#8220;center&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8220;row&#8220; _builder_version=&#8220;3.25&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Text&#8220; _builder_version=&#8220;3.27.4&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; text_orientation=&#8220;left&#8220; use_border_color=&#8220;off&#8220; border_color=&#8220;#ffffff&#8220; border_style=&#8220;solid&#8220; saved_tabs=&#8220;all&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h1>creditshelf startet zusammen mit CrossLend die erste digitale Verbriefung von Mittelstandskrediten<\/h1>\n<ul>\n<li>Digitale Verbriefung von auf der creditshelf-Plattform originierten Kreditforderungen \u00fcber neuen Partner CrossLend<\/li>\n<li>Verbriefung \u00fcber CrossLend f\u00fchrt zu weiterer Diversifizierung und Verbreiterung des Investoren-Pools<\/li>\n<li>Monatliche Investition eines mittleren einstelligen Millionenbetrags in das Neugesch\u00e4ft von creditshelf durch einen institutionellen Investor<\/li>\n<\/ul>\n<p>Frankfurt am Main, 18. Dezember 2018 \u2013 Die creditshelf Aktiengesellschaft, ein Pionier im Bereich der digitalen Mittelstandsfinanzierung in Deutschland, startet eine Partnerschaft mit dem Kreditmarktplatz CrossLend, um deutschlandweit erstmals eine digitale Verbriefung von Mittelstandskrediten anzubieten. Dabei tritt CrossLend als Investor auf der creditshelf-Plattform auf und kauft Kreditforderungen im Rahmen der regul\u00e4ren Kreditvergabeprozesse an. Anschlie\u00dfend verbrieft CrossLend die Kreditforderungen und bietet diese so in Form eines neuen Produkts einer breiten Basis von zus\u00e4tzlichen Investoren \u00fcber die eigenen Kan\u00e4le an. Zu Beginn wird ein institutioneller Investor \u00fcber CrossLend monatlich einen mittleren einstelligen Millionenbetrag in das Neugesch\u00e4ft von creditshelf investieren.<br \/>\nF\u00fcr das neue Angebot werden die Kredite bereits bei der Generierung so angelegt, dass sie entweder unmittelbar oder mit zeitlichem Verzug an institutionelle Investoren weitergegeben werden k\u00f6nnen. \u201eMit der flexiblen Verbriefung von Mittelstandskrediten bieten wir ein neues, innovatives Produkt\u201c, sagt Dr. Daniel Bartsch, Vorstand und Gr\u00fcndungspartner von creditshelf. \u201eDer vollautomatisierte Prozess erh\u00f6ht die Transparenz der resultierenden Wertpapiere, schafft Fungibilit\u00e4t und erm\u00f6glicht es, die Transaktionskosten gering zu halten. Dieses Modell er\u00f6ffnet uns neue Investorenkreise und kommt damit auch unseren Kunden zugute.&#8220;<br \/>\nAbgewickelt wird die Verbriefung \u00fcber die digitale Verbriefungsplattform von CrossLend. Das Berliner Fintech-Unternehmen wandelt die Kredite auf flexible und transparente Art und Weise in Schuldverschreibungen um. \u201eUnsere Plattform war von Anfang an darauf ausgelegt, den Kreditmarkt effizienter, transparenter und digitaler zu gestalten. Die Zusammenarbeit mit creditshelf bei der Echtzeitverbriefung von Mittelstandskrediten bringt uns auf diesem Weg wieder ein gro\u00dfes St\u00fcck weiter&#8220;, sagt Oliver Schimek, CEO von CrossLend. Die Partnerschaft startet mit einem ersten institutionellen Investor, der durch monatliche Investitionen in das Kreditneugesch\u00e4ft von creditshelf \u00fcber CrossLend sukzessive ein Kreditportfolio im mittleren zweistelligen Millionenbetrag pro Jahr aufbauen wird. Daneben befinden sich weitere institutionelle Investoren in der Pipeline, die ebenfalls \u00fcber diese innovative L\u00f6sung in Mittelstandskredite investieren m\u00f6chten. \u201eWir freuen uns, \u00fcber die Zusammenarbeit mit CrossLend einen zus\u00e4tzlichen Vertriebskanal anzubieten und damit k\u00fcnftig weitere institutionelle Kreditinvestoren f\u00fcr uns gewinnen\u201c, so creditshelf-Vorstand Bartsch.<\/p>\n<p><strong>Weitere Informationen:<\/strong><br \/>\ncreditshelf Aktiengesellschaft<br \/>\nBirgit Hass<br \/>\nHead of Marketing and Communication<br \/>\nMainzer Landstra\u00dfe 33a<br \/>\n60329 Frankfurt<br \/>\nTel.: +49 (69) 348 77 24-13<br \/>\nbirgit.hass@creditshelf.com<br \/>\nwww.creditshelf.com<\/p>\n<p><strong>crossLend GmbH<\/strong><br \/>\nAgnieszka Szczesna<br \/>\nCommunications Manager<br \/>\nKemperplatz 1<br \/>\n10785 Berlin<br \/>\nTel.: +49 (151) 756 98 507<br \/>\nagnieszka.szczesna@crosslend.com<br \/>\nwww.crosslend.com<\/p>\n<p><strong>Presse- und \u00d6ffentlichkeitarbeit:<\/strong><br \/>\nTh\u00f6ring &amp; Stuhr<br \/>\nPartnerschaft f\u00fcr Kommunikationsberatung<br \/>\nArne Stuhr<br \/>\nManaging director<br \/>\nMittelweg 142<br \/>\n20148 Hamburg<br \/>\nTel: +49 (40 )207 6969 83<br \/>\nMobil: +49 (177) 3055 194<br \/>\narne.stuhr@corpnewsmedia.de<\/p>\n<p><strong>Investor Relations:<\/strong><br \/>\ncometis AG<br \/>\nMaximilian Franz<br \/>\nUnter den Eichen 7<br \/>\n65195 Wiesbaden<br \/>\nTel: +49 (611) 20 585-0<br \/>\nfranz@dev.cometis.de<br \/>\nwww.www.cometis.de<\/p>\n<p><strong>\u00dcber creditshelf \u2013 www.creditshelf.com<\/strong><br \/>\ncreditshelf ist ein Pionier im Bereich der digitalen Mittelstandsfinanzierung in Deutschland, der \u00fcber seine leicht zu bedienende Online-Plattform www.creditshelf.com Kredite erm\u00f6glicht. Die im Jahr 2014 gegr\u00fcndete creditshelf mit Sitz in Frankfurt am Main versteht sich als Markt- und Technologief\u00fchrer im wachstumsstarken Gesch\u00e4ft der digitalen Mittelstandsfinanzierung in Deutschland. Als Mittelstandsfinanzierer hat creditshelf seine Plattform entwickelt, um den Finanzierungsbedarf von deutschen KMU-Kreditnehmern durch Kredite von an dieser Anlageklasse interessierten Investoren zu bedienen. In diesem Prozess bietet creditshelf an, unbesicherte Kredite zu vermitteln, und erm\u00f6glicht kleinen und mittelst\u00e4ndischen Unternehmen so den Zugang zu hochattraktiven Finanzierungsalternativen. Gleichzeitig bietet das Unternehmen professionellen Investoren auf der Suche nach attraktiven Anlagem\u00f6glichkeiten Zugang zur KMU-Finanzierung. Zu den Kernkompetenzen von creditshelf z\u00e4hlen die Auswahl geeigneter Kreditprojekte, die Analyse der Kreditw\u00fcrdigkeit potenzieller Kreditnehmer und die Bereitstellung eines Kreditscorings sowie einer indikativen Kouponspanne. F\u00fcr ihre Dienstleistungen erh\u00e4lt creditshelf sowohl von den KMU-Kreditnehmern als auch von den Investoren Geb\u00fchren.<br \/>\nT\u00e4gliche News von creditshelf auf<br \/>\nFacebook https:\/\/www.facebook.com\/creditshelf\/<br \/>\nTwitter https:\/\/twitter.com\/creditshelf<br \/>\nLinkedIn https:\/\/www.linkedin.com\/company\/5317762\/ und<br \/>\nXing https:\/\/www.xing.com\/xbp\/pages\/creditshelf-ag<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8220;Schaltfl\u00e4che %22Beitrag als PDF%22&#8243; _builder_version=&#8220;3.27.4&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; text_orientation=&#8220;left&#8220; use_border_color=&#8220;off&#8220; border_color=&#8220;#ffffff&#8220; border_style=&#8220;solid&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<div class=\"leseprobe-archiv\"><a title=\"Beitrag als PDF\" href=\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2018\/12\/181210_CN_Verbriefung_CrossLend_de_cometis_ts_final.pdf\" target=\"_blank\" rel=\"noopener\">Beitrag als PDF<\/a><\/div>\n<style> .leseprobe-archiv {color: #00225f !important; border-color: #00225f; position: relative; padding: 0.3em 1em; border: 1px solid; -webkit-border-radius: 3px; -moz-border-radius: 3px; border-radius: 3px; -webkit-transition: all 0.2s; -moz-transition: all 0.2s; transition: all 0.2s; padding:10px; width: 19%; text-align: center; margin-right: 10px; float:left;} .leseprobe-archiv:hover {background-color: #eee; border-color: #ffffff; cursor: pointer;}<\/style>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;section&#8220; _builder_version=&#8220;3.22&#8243; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220; da_disable_devices=&#8220;off|off|off&#8220;][et_pb_row admin_label=&#8220;row&#8220; _builder_version=&#8220;3.25&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Corporate News zum Archiv creditshelf startet zusammen mit CrossLend die erste digitale Verbriefung von Mittelstandskrediten Digitale Verbriefung von auf der creditshelf-Plattform originierten Kreditforderungen \u00fcber neuen Partner CrossLend Verbriefung \u00fcber CrossLend f\u00fchrt zu weiterer Diversifizierung und Verbreiterung des Investoren-Pools Monatliche Investition eines mittleren einstelligen Millionenbetrags in das Neugesch\u00e4ft von creditshelf durch einen institutionellen Investor Frankfurt am [&hellip;]<\/p>\n","protected":false},"author":24813,"featured_media":54373,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[285,447],"tags":[498],"class_list":["post-22418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-creditshelf-corporate-news","category-news","tag-498"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>18. Dezember 2018 | creditshelf startet zusammen mit CrossLend die erste digitale Verbriefung von Mittelstandskrediten - cometis AG<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"18. Dezember 2018 | creditshelf startet zusammen mit CrossLend die erste digitale Verbriefung von Mittelstandskrediten - cometis AG\" \/>\n<meta property=\"og:description\" content=\"Corporate News zum Archiv creditshelf startet zusammen mit CrossLend die erste digitale Verbriefung von Mittelstandskrediten Digitale Verbriefung von auf der creditshelf-Plattform originierten Kreditforderungen \u00fcber neuen Partner CrossLend Verbriefung \u00fcber CrossLend f\u00fchrt zu weiterer Diversifizierung und Verbreiterung des Investoren-Pools Monatliche Investition eines mittleren einstelligen Millionenbetrags in das Neugesch\u00e4ft von creditshelf durch einen institutionellen Investor Frankfurt am [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.cometis.de\/de\/18-dezember-2018-creditshelf-startet-zusammen-mit-crosslend-die-erste-digitale-verbriefung-von-mittelstandskrediten\/\" \/>\n<meta property=\"og:site_name\" content=\"cometis AG\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-18T06:45:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-14T04:28:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Assistenz cometis AG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Assistenz cometis AG\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.cometis.de\/de\/18-dezember-2018-creditshelf-startet-zusammen-mit-crosslend-die-erste-digitale-verbriefung-von-mittelstandskrediten\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/18-dezember-2018-creditshelf-startet-zusammen-mit-crosslend-die-erste-digitale-verbriefung-von-mittelstandskrediten\/\"},\"author\":{\"name\":\"Assistenz cometis AG\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/0f6ec71e9167dd48a24950f3cc6b2003\"},\"headline\":\"18. Dezember 2018 | creditshelf startet zusammen mit CrossLend die erste digitale Verbriefung von Mittelstandskrediten\",\"datePublished\":\"2018-12-18T06:45:17+00:00\",\"dateModified\":\"2022-03-14T04:28:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/18-dezember-2018-creditshelf-startet-zusammen-mit-crosslend-die-erste-digitale-verbriefung-von-mittelstandskrediten\/\"},\"wordCount\":1130,\"publisher\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/18-dezember-2018-creditshelf-startet-zusammen-mit-crosslend-die-erste-digitale-verbriefung-von-mittelstandskrediten\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg\",\"keywords\":[\"2018\"],\"articleSection\":[\"creditshelf Corporate News\",\"News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.cometis.de\/de\/18-dezember-2018-creditshelf-startet-zusammen-mit-crosslend-die-erste-digitale-verbriefung-von-mittelstandskrediten\/\",\"url\":\"https:\/\/dev.cometis.de\/de\/18-dezember-2018-creditshelf-startet-zusammen-mit-crosslend-die-erste-digitale-verbriefung-von-mittelstandskrediten\/\",\"name\":\"18. Dezember 2018 | creditshelf startet zusammen mit CrossLend die erste digitale Verbriefung von Mittelstandskrediten - cometis AG\",\"isPartOf\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/18-dezember-2018-creditshelf-startet-zusammen-mit-crosslend-die-erste-digitale-verbriefung-von-mittelstandskrediten\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/18-dezember-2018-creditshelf-startet-zusammen-mit-crosslend-die-erste-digitale-verbriefung-von-mittelstandskrediten\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg\",\"datePublished\":\"2018-12-18T06:45:17+00:00\",\"dateModified\":\"2022-03-14T04:28:23+00:00\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.cometis.de\/de\/18-dezember-2018-creditshelf-startet-zusammen-mit-crosslend-die-erste-digitale-verbriefung-von-mittelstandskrediten\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dev.cometis.de\/de\/18-dezember-2018-creditshelf-startet-zusammen-mit-crosslend-die-erste-digitale-verbriefung-von-mittelstandskrediten\/#primaryimage\",\"url\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg\",\"contentUrl\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg\",\"caption\":\"Icon Newsroom_news\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#website\",\"url\":\"https:\/\/dev.cometis.de\/de\/\",\"name\":\"cometis AG\",\"description\":\"Deutschlands f\u00fchrende Investor Relations Agentur\",\"publisher\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.cometis.de\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#organization\",\"name\":\"cometis AG\",\"alternateName\":\"Deutschlands f\u00fchrende Investor Relations Agentur\",\"url\":\"https:\/\/dev.cometis.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/01\/Cometis-Mobile-Logo-1.png\",\"contentUrl\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/01\/Cometis-Mobile-Logo-1.png\",\"width\":171,\"height\":31,\"caption\":\"cometis AG\"},\"image\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/0f6ec71e9167dd48a24950f3cc6b2003\",\"name\":\"Assistenz cometis AG\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d9db77bcddbfa0c99848135c21ae5b93?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d9db77bcddbfa0c99848135c21ae5b93?s=96&d=mm&r=g\",\"caption\":\"Assistenz cometis AG\"},\"url\":\"https:\/\/dev.cometis.de\/de\/author\/assistenz-cometis-ag\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"18. Dezember 2018 | creditshelf startet zusammen mit CrossLend die erste digitale Verbriefung von Mittelstandskrediten - cometis AG","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"18. Dezember 2018 | creditshelf startet zusammen mit CrossLend die erste digitale Verbriefung von Mittelstandskrediten - cometis AG","og_description":"Corporate News zum Archiv creditshelf startet zusammen mit CrossLend die erste digitale Verbriefung von Mittelstandskrediten Digitale Verbriefung von auf der creditshelf-Plattform originierten Kreditforderungen \u00fcber neuen Partner CrossLend Verbriefung \u00fcber CrossLend f\u00fchrt zu weiterer Diversifizierung und Verbreiterung des Investoren-Pools Monatliche Investition eines mittleren einstelligen Millionenbetrags in das Neugesch\u00e4ft von creditshelf durch einen institutionellen Investor Frankfurt am [&hellip;]","og_url":"https:\/\/dev.cometis.de\/de\/18-dezember-2018-creditshelf-startet-zusammen-mit-crosslend-die-erste-digitale-verbriefung-von-mittelstandskrediten\/","og_site_name":"cometis AG","article_published_time":"2018-12-18T06:45:17+00:00","article_modified_time":"2022-03-14T04:28:23+00:00","og_image":[{"url":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg","width":1,"height":1,"type":"image\/png"}],"author":"Assistenz cometis AG","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Assistenz cometis AG","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.cometis.de\/de\/18-dezember-2018-creditshelf-startet-zusammen-mit-crosslend-die-erste-digitale-verbriefung-von-mittelstandskrediten\/#article","isPartOf":{"@id":"https:\/\/dev.cometis.de\/de\/18-dezember-2018-creditshelf-startet-zusammen-mit-crosslend-die-erste-digitale-verbriefung-von-mittelstandskrediten\/"},"author":{"name":"Assistenz cometis AG","@id":"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/0f6ec71e9167dd48a24950f3cc6b2003"},"headline":"18. Dezember 2018 | creditshelf startet zusammen mit CrossLend die erste digitale Verbriefung von Mittelstandskrediten","datePublished":"2018-12-18T06:45:17+00:00","dateModified":"2022-03-14T04:28:23+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.cometis.de\/de\/18-dezember-2018-creditshelf-startet-zusammen-mit-crosslend-die-erste-digitale-verbriefung-von-mittelstandskrediten\/"},"wordCount":1130,"publisher":{"@id":"https:\/\/dev.cometis.de\/de\/#organization"},"image":{"@id":"https:\/\/dev.cometis.de\/de\/18-dezember-2018-creditshelf-startet-zusammen-mit-crosslend-die-erste-digitale-verbriefung-von-mittelstandskrediten\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg","keywords":["2018"],"articleSection":["creditshelf Corporate News","News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/dev.cometis.de\/de\/18-dezember-2018-creditshelf-startet-zusammen-mit-crosslend-die-erste-digitale-verbriefung-von-mittelstandskrediten\/","url":"https:\/\/dev.cometis.de\/de\/18-dezember-2018-creditshelf-startet-zusammen-mit-crosslend-die-erste-digitale-verbriefung-von-mittelstandskrediten\/","name":"18. Dezember 2018 | creditshelf startet zusammen mit CrossLend die erste digitale Verbriefung von Mittelstandskrediten - cometis AG","isPartOf":{"@id":"https:\/\/dev.cometis.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.cometis.de\/de\/18-dezember-2018-creditshelf-startet-zusammen-mit-crosslend-die-erste-digitale-verbriefung-von-mittelstandskrediten\/#primaryimage"},"image":{"@id":"https:\/\/dev.cometis.de\/de\/18-dezember-2018-creditshelf-startet-zusammen-mit-crosslend-die-erste-digitale-verbriefung-von-mittelstandskrediten\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg","datePublished":"2018-12-18T06:45:17+00:00","dateModified":"2022-03-14T04:28:23+00:00","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.cometis.de\/de\/18-dezember-2018-creditshelf-startet-zusammen-mit-crosslend-die-erste-digitale-verbriefung-von-mittelstandskrediten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dev.cometis.de\/de\/18-dezember-2018-creditshelf-startet-zusammen-mit-crosslend-die-erste-digitale-verbriefung-von-mittelstandskrediten\/#primaryimage","url":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg","contentUrl":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg","caption":"Icon Newsroom_news"},{"@type":"WebSite","@id":"https:\/\/dev.cometis.de\/de\/#website","url":"https:\/\/dev.cometis.de\/de\/","name":"cometis AG","description":"Deutschlands f\u00fchrende Investor Relations Agentur","publisher":{"@id":"https:\/\/dev.cometis.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.cometis.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dev.cometis.de\/de\/#organization","name":"cometis AG","alternateName":"Deutschlands f\u00fchrende Investor Relations Agentur","url":"https:\/\/dev.cometis.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dev.cometis.de\/de\/#\/schema\/logo\/image\/","url":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/01\/Cometis-Mobile-Logo-1.png","contentUrl":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/01\/Cometis-Mobile-Logo-1.png","width":171,"height":31,"caption":"cometis AG"},"image":{"@id":"https:\/\/dev.cometis.de\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/0f6ec71e9167dd48a24950f3cc6b2003","name":"Assistenz cometis AG","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d9db77bcddbfa0c99848135c21ae5b93?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d9db77bcddbfa0c99848135c21ae5b93?s=96&d=mm&r=g","caption":"Assistenz cometis AG"},"url":"https:\/\/dev.cometis.de\/de\/author\/assistenz-cometis-ag\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/posts\/22418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/users\/24813"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/comments?post=22418"}],"version-history":[{"count":2,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/posts\/22418\/revisions"}],"predecessor-version":[{"id":56176,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/posts\/22418\/revisions\/56176"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/media\/54373"}],"wp:attachment":[{"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/media?parent=22418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/categories?post=22418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/tags?post=22418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}