{"id":16885,"date":"2016-11-10T11:01:38","date_gmt":"2016-11-10T10:01:38","guid":{"rendered":"https:\/\/wordpress-783423-2671269.cloudwaysapps.com\/?p=16885"},"modified":"2022-03-11T05:18:10","modified_gmt":"2022-03-11T04:18:10","slug":"10-november-2016-corestate-capital-holding-s-a-corestate-entwickelt-wohnprojekt-fuer-studenten-in-madrid","status":"publish","type":"post","link":"https:\/\/dev.cometis.de\/de\/10-november-2016-corestate-capital-holding-s-a-corestate-entwickelt-wohnprojekt-fuer-studenten-in-madrid\/","title":{"rendered":"10. November 2016 | Corestate Capital Holding S.A.: CORESTATE entwickelt Wohnprojekt f\u00fcr Studenten in Madrid"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;section&#8220; _builder_version=&#8220;3.22&#8243; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220; da_disable_devices=&#8220;off|off|off&#8220;][et_pb_row padding_mobile=&#8220;off&#8220; column_padding_mobile=&#8220;on&#8220; admin_label=&#8220;Zeile&#8220; _builder_version=&#8220;3.25&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; custom_padding=&#8220;||0px|&#8220; make_fullwidth=&#8220;off&#8220; use_custom_width=&#8220;off&#8220; width_unit=&#8220;on&#8220; global_colors_info=&#8220;{}&#8220; column_structure=&#8220;1_2,1_2&#8243;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Text&#8220; _builder_version=&#8220;3.27.4&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; text_orientation=&#8220;left&#8220; use_border_color=&#8220;off&#8220; border_color=&#8220;#ffffff&#8220; border_style=&#8220;solid&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<style>\n.zur\u00fcckbutton:before {\n    display: inline-block;\n    font-family: \"ETmodules\";\n    content: \"\\4a\";\n    color: #00225f;\n    margin-right: 7px;\n}\n.zur\u00fcckbutton:hover:before {\n    display: inline-block;\n    font-family: \"ETmodules\";\n    content: \"\\4a\";\n    color: #d85710;\n    margin-right: 7px;\n}\n<\/style>\n<h1 style=\"text-align: justify;\">Corporate News<\/h1>\n<p> <a class=\"zur\u00fcckbutton\" href=\"https:\/\/dev.cometis.de\/veroeffentlichungsarchiv-corestate\">zum Archiv<\/a><br \/>\n[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/dev.cometis.de\/wp-content\/uploads\/2018\/08\/Corestate-Capital-Group-1.png&#8220; align=&#8220;right&#8220; align_tablet=&#8220;center&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;Bild&#8220; _builder_version=&#8220;3.23&#8243; use_border_color=&#8220;off&#8220; border_color=&#8220;#ffffff&#8220; border_style=&#8220;solid&#8220; animation=&#8220;off&#8220; sticky=&#8220;off&#8220; always_center_on_mobile=&#8220;on&#8220; global_colors_info=&#8220;{}&#8220; align_phone=&#8220;center&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8220;row&#8220; _builder_version=&#8220;3.25&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Text&#8220; _builder_version=&#8220;3.27.4&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; text_orientation=&#8220;left&#8220; use_border_color=&#8220;off&#8220; border_color=&#8220;#ffffff&#8220; border_style=&#8220;solid&#8220; saved_tabs=&#8220;all&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h1><b>Corestate Capital Holding S.A.: CORESTATE entwickelt Wohnprojekt f\u00fcr Studenten in Madrid<\/b><\/h1>\n<p>&nbsp;<\/p>\n<div class=\"break-word news_main\">\n<p>Die CORESTATE Capital Holding S.A. (&#8222;CORESTATE&#8220;), ein vollintegrierter Immobilien-Investmentmanager und Co-Investor, hat ein Sanierungsobjekt in Madrid erworben, um in der spanischen Hauptstadt ein Wohnprojekt f\u00fcr Studenten zu realisieren. Derzeitige Planungen sehen eine Gesamtmietfl\u00e4che von 4.022 m<sup>2\u00a0<\/sup>vor mit 260 Zimmern und 302 Betten.<\/p>\n<p>Das Bestandsobjekt, das 44 Jahre lang als Studentenwohnheim betrieben wurde, liegt im Stadtteil &#8218;Ciudad Universitaria&#8216;, einem Wohngebiet mit neun Universit\u00e4ten und \u00fcber 120.000 Studenten. CORESTATE plant den bestehenden Wohnkomplex abzurei\u00dfen und in einem n\u00e4chsten Schritt ein neues Geb\u00e4ude zu errichten, mit dem Anspruch eines der bestausgestatteten studentischen Wohnprojekte in Madrid zu realisieren. Der Geb\u00e4udekomplex wird eine hochwertige Ausstattung bieten, inklusive Lobby mit Rezeption und Concierge-Service, Gemeinschaftsr\u00e4ume, Restaurant, Fitnessstudio und Washing Lounges sowie Au\u00dfenbereiche wie Garten, Dachterrassen und Innenh\u00f6fe.<\/p>\n<p>Alle Zimmer sind komplett m\u00f6bliert und haben ein eigenes Badezimmer. Neben einem schnellen Internetzugang geh\u00f6ren auch Vollpension (drei Mahlzeiten am Tag), eine w\u00f6chentliche Reinigung und andere hauswirtschaftliche Angebote zu den im Preis eingeschlossenen Dienstleistungen.<\/p>\n<p>&#8222;Madrid ist ein sehr beliebter Standort f\u00fcr spanische und ausl\u00e4ndische Studenten, da es hier zahlreiche \u00f6ffentliche und private Universit\u00e4ten gibt, die eine Vielzahl von Bachelor- und Master-Studieng\u00e4ngen anbieten. Aufgrund der hohen Nachfrage im Mietmarkt sowie der au\u00dferordentlich attraktiven Lage des Wohnkomplexes gehen wir fest davon aus, dass Mieter dieses Projekt sehr gut annehmen werden&#8220;,<b>\u00a0<\/b>so Thomas Landschreiber, Chief Investment Officer von CORESTATE.<\/p>\n<p><b>IR Kontakt<\/b><br \/>\nDr. Kai Gregor Klinger<br \/>\nT: +49 69 3535630107 \/ M: +49 152 22755400<br \/>\nir@corestate-capital.com<\/p>\n<p><b>PR Kontakt<\/b><br \/>\nAndre Zahlten<br \/>\nT: +49 69 3535630-108 \/ M: +49 174 4022348<br \/>\nandre.zahlten@corestate-capital.com<\/p>\n<p><b>\u00dcber CORESTATE Capital Holding S.A.<\/b><br \/>\nCORESTATE Capital Holding S.A. (CORESTATE) ist ein Investmentmanager und Co-Investor mit einem verwalteten Verm\u00f6gen von ca. EUR 22 Mrd. Als eine voll integrierte Immobilien-Plattform bietet CORESTATE seinen Kunden fundierte Expertise in den Bereichen Investment- und Fonds Management sowie Immobilien-Management Services aus einer Hand. Das Unternehmen ist international als angesehener Gesch\u00e4ftspartner f\u00fcr institutionelle Investoren sowie verm\u00f6gende Privatanleger t\u00e4tig. Die Gesellschaft hat ihren Hauptsitz in Luxemburg und verf\u00fcgt \u00fcber 41 weitere B\u00fcros unter anderen in Frankfurt, London, Madrid, Singapur und Z\u00fcrich. CORESTATE besch\u00e4ftigt \u00fcber 560 Mitarbeiter und ist an der Frankfurter Wertpapierb\u00f6rse (SDAX) notiert. Weitere Informationen finden Sie unter\u00a0<a href=\"https:\/\/link.cockpit.eqs.com\/cgi-bin\/fncls.ssp?fn=redirect&amp;url=38751e2f663f4d4fb04067870e000bf8&amp;application_id=709761&amp;site_id=news_data&amp;application_name=news\" target=\"_blank\" rel=\"noopener\">www.corestate-capital.com<\/a>.<\/p>\n<p><b>Zukunftsgerichtete Aussagen<\/b><br \/>\nDiese Pressemitteilung kann bestimmte in die Zukunft gerichtete Aussagen enthalten, die auf den gegenw\u00e4rtigen Annahmen und Prognosen unserer Unternehmensleitung beruhen. Verschiedene bekannte wie auch unbekannte Risiken, Ungewissheiten und andere Faktoren k\u00f6nnen dazu f\u00fchren, dass die tats\u00e4chlichen Ergebnisse, die Finanzlage, die Entwicklung oder die Performance unserer Gesellschaft wesentlich von den hier gegebenen Einsch\u00e4tzungen abweichen. Diese Faktoren schlie\u00dfen diejenigen ein, die wir in ver\u00f6ffentlichten Berichten beschrieben haben. Diese Berichte stehen auf unserer Webseite ir.corestate-capital.com zur Verf\u00fcgung. Die Gesellschaft \u00fcbernimmt keinerlei Verpflichtung, solche zukunftsgerichteten Aussagen fortzuschreiben und an zuk\u00fcnftige Ereignisse oder Entwicklungen anzupassen. Zukunftsgerichteten Aussagen, deren Wirkung lediglich auf das Datum dieser Mitteilung abstellt, sollten keine unangemessene Bedeutung beigemessen werden.<\/p>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Corporate News zum Archiv Corestate Capital Holding S.A.: CORESTATE entwickelt Wohnprojekt f\u00fcr Studenten in Madrid &nbsp; Die CORESTATE Capital Holding S.A. (&#8222;CORESTATE&#8220;), ein vollintegrierter Immobilien-Investmentmanager und Co-Investor, hat ein Sanierungsobjekt in Madrid erworben, um in der spanischen Hauptstadt ein Wohnprojekt f\u00fcr Studenten zu realisieren. Derzeitige Planungen sehen eine Gesamtmietfl\u00e4che von 4.022 m2\u00a0vor mit 260 Zimmern [&hellip;]<\/p>\n","protected":false},"author":24813,"featured_media":54373,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[281,447],"tags":[500],"class_list":["post-16885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-corestate-corporate-news","category-news","tag-500"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>10. November 2016 | Corestate Capital Holding S.A.: CORESTATE entwickelt Wohnprojekt f\u00fcr Studenten in Madrid - cometis AG<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10. November 2016 | Corestate Capital Holding S.A.: CORESTATE entwickelt Wohnprojekt f\u00fcr Studenten in Madrid - cometis AG\" \/>\n<meta property=\"og:description\" content=\"Corporate News zum Archiv Corestate Capital Holding S.A.: CORESTATE entwickelt Wohnprojekt f\u00fcr Studenten in Madrid &nbsp; Die CORESTATE Capital Holding S.A. (&quot;CORESTATE&quot;), ein vollintegrierter Immobilien-Investmentmanager und Co-Investor, hat ein Sanierungsobjekt in Madrid erworben, um in der spanischen Hauptstadt ein Wohnprojekt f\u00fcr Studenten zu realisieren. Derzeitige Planungen sehen eine Gesamtmietfl\u00e4che von 4.022 m2\u00a0vor mit 260 Zimmern [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.cometis.de\/de\/10-november-2016-corestate-capital-holding-s-a-corestate-entwickelt-wohnprojekt-fuer-studenten-in-madrid\/\" \/>\n<meta property=\"og:site_name\" content=\"cometis AG\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-10T10:01:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-11T04:18:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Assistenz cometis AG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Assistenz cometis AG\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.cometis.de\/de\/10-november-2016-corestate-capital-holding-s-a-corestate-entwickelt-wohnprojekt-fuer-studenten-in-madrid\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/10-november-2016-corestate-capital-holding-s-a-corestate-entwickelt-wohnprojekt-fuer-studenten-in-madrid\/\"},\"author\":{\"name\":\"Assistenz cometis AG\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/0f6ec71e9167dd48a24950f3cc6b2003\"},\"headline\":\"10. November 2016 | Corestate Capital Holding S.A.: CORESTATE entwickelt Wohnprojekt f\u00fcr Studenten in Madrid\",\"datePublished\":\"2016-11-10T10:01:38+00:00\",\"dateModified\":\"2022-03-11T04:18:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/10-november-2016-corestate-capital-holding-s-a-corestate-entwickelt-wohnprojekt-fuer-studenten-in-madrid\/\"},\"wordCount\":830,\"publisher\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/10-november-2016-corestate-capital-holding-s-a-corestate-entwickelt-wohnprojekt-fuer-studenten-in-madrid\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg\",\"keywords\":[\"2016\"],\"articleSection\":[\"CORESTATE Corporate News\",\"News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.cometis.de\/de\/10-november-2016-corestate-capital-holding-s-a-corestate-entwickelt-wohnprojekt-fuer-studenten-in-madrid\/\",\"url\":\"https:\/\/dev.cometis.de\/de\/10-november-2016-corestate-capital-holding-s-a-corestate-entwickelt-wohnprojekt-fuer-studenten-in-madrid\/\",\"name\":\"10. November 2016 | Corestate Capital Holding S.A.: CORESTATE entwickelt Wohnprojekt f\u00fcr Studenten in Madrid - cometis AG\",\"isPartOf\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/10-november-2016-corestate-capital-holding-s-a-corestate-entwickelt-wohnprojekt-fuer-studenten-in-madrid\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/10-november-2016-corestate-capital-holding-s-a-corestate-entwickelt-wohnprojekt-fuer-studenten-in-madrid\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg\",\"datePublished\":\"2016-11-10T10:01:38+00:00\",\"dateModified\":\"2022-03-11T04:18:10+00:00\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.cometis.de\/de\/10-november-2016-corestate-capital-holding-s-a-corestate-entwickelt-wohnprojekt-fuer-studenten-in-madrid\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dev.cometis.de\/de\/10-november-2016-corestate-capital-holding-s-a-corestate-entwickelt-wohnprojekt-fuer-studenten-in-madrid\/#primaryimage\",\"url\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg\",\"contentUrl\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg\",\"caption\":\"Icon Newsroom_news\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#website\",\"url\":\"https:\/\/dev.cometis.de\/de\/\",\"name\":\"cometis AG\",\"description\":\"Deutschlands f\u00fchrende Investor Relations Agentur\",\"publisher\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.cometis.de\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#organization\",\"name\":\"cometis AG\",\"alternateName\":\"Deutschlands f\u00fchrende Investor Relations Agentur\",\"url\":\"https:\/\/dev.cometis.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/01\/Cometis-Mobile-Logo-1.png\",\"contentUrl\":\"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/01\/Cometis-Mobile-Logo-1.png\",\"width\":171,\"height\":31,\"caption\":\"cometis AG\"},\"image\":{\"@id\":\"https:\/\/dev.cometis.de\/de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/0f6ec71e9167dd48a24950f3cc6b2003\",\"name\":\"Assistenz cometis AG\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d9db77bcddbfa0c99848135c21ae5b93?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d9db77bcddbfa0c99848135c21ae5b93?s=96&d=mm&r=g\",\"caption\":\"Assistenz cometis AG\"},\"url\":\"https:\/\/dev.cometis.de\/de\/author\/assistenz-cometis-ag\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10. November 2016 | Corestate Capital Holding S.A.: CORESTATE entwickelt Wohnprojekt f\u00fcr Studenten in Madrid - cometis AG","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"10. November 2016 | Corestate Capital Holding S.A.: CORESTATE entwickelt Wohnprojekt f\u00fcr Studenten in Madrid - cometis AG","og_description":"Corporate News zum Archiv Corestate Capital Holding S.A.: CORESTATE entwickelt Wohnprojekt f\u00fcr Studenten in Madrid &nbsp; Die CORESTATE Capital Holding S.A. (\"CORESTATE\"), ein vollintegrierter Immobilien-Investmentmanager und Co-Investor, hat ein Sanierungsobjekt in Madrid erworben, um in der spanischen Hauptstadt ein Wohnprojekt f\u00fcr Studenten zu realisieren. Derzeitige Planungen sehen eine Gesamtmietfl\u00e4che von 4.022 m2\u00a0vor mit 260 Zimmern [&hellip;]","og_url":"https:\/\/dev.cometis.de\/de\/10-november-2016-corestate-capital-holding-s-a-corestate-entwickelt-wohnprojekt-fuer-studenten-in-madrid\/","og_site_name":"cometis AG","article_published_time":"2016-11-10T10:01:38+00:00","article_modified_time":"2022-03-11T04:18:10+00:00","og_image":[{"url":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg","width":1,"height":1,"type":"image\/png"}],"author":"Assistenz cometis AG","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Assistenz cometis AG","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.cometis.de\/de\/10-november-2016-corestate-capital-holding-s-a-corestate-entwickelt-wohnprojekt-fuer-studenten-in-madrid\/#article","isPartOf":{"@id":"https:\/\/dev.cometis.de\/de\/10-november-2016-corestate-capital-holding-s-a-corestate-entwickelt-wohnprojekt-fuer-studenten-in-madrid\/"},"author":{"name":"Assistenz cometis AG","@id":"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/0f6ec71e9167dd48a24950f3cc6b2003"},"headline":"10. November 2016 | Corestate Capital Holding S.A.: CORESTATE entwickelt Wohnprojekt f\u00fcr Studenten in Madrid","datePublished":"2016-11-10T10:01:38+00:00","dateModified":"2022-03-11T04:18:10+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.cometis.de\/de\/10-november-2016-corestate-capital-holding-s-a-corestate-entwickelt-wohnprojekt-fuer-studenten-in-madrid\/"},"wordCount":830,"publisher":{"@id":"https:\/\/dev.cometis.de\/de\/#organization"},"image":{"@id":"https:\/\/dev.cometis.de\/de\/10-november-2016-corestate-capital-holding-s-a-corestate-entwickelt-wohnprojekt-fuer-studenten-in-madrid\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg","keywords":["2016"],"articleSection":["CORESTATE Corporate News","News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/dev.cometis.de\/de\/10-november-2016-corestate-capital-holding-s-a-corestate-entwickelt-wohnprojekt-fuer-studenten-in-madrid\/","url":"https:\/\/dev.cometis.de\/de\/10-november-2016-corestate-capital-holding-s-a-corestate-entwickelt-wohnprojekt-fuer-studenten-in-madrid\/","name":"10. November 2016 | Corestate Capital Holding S.A.: CORESTATE entwickelt Wohnprojekt f\u00fcr Studenten in Madrid - cometis AG","isPartOf":{"@id":"https:\/\/dev.cometis.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.cometis.de\/de\/10-november-2016-corestate-capital-holding-s-a-corestate-entwickelt-wohnprojekt-fuer-studenten-in-madrid\/#primaryimage"},"image":{"@id":"https:\/\/dev.cometis.de\/de\/10-november-2016-corestate-capital-holding-s-a-corestate-entwickelt-wohnprojekt-fuer-studenten-in-madrid\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg","datePublished":"2016-11-10T10:01:38+00:00","dateModified":"2022-03-11T04:18:10+00:00","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.cometis.de\/de\/10-november-2016-corestate-capital-holding-s-a-corestate-entwickelt-wohnprojekt-fuer-studenten-in-madrid\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dev.cometis.de\/de\/10-november-2016-corestate-capital-holding-s-a-corestate-entwickelt-wohnprojekt-fuer-studenten-in-madrid\/#primaryimage","url":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg","contentUrl":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/03\/icon_newsroom.svg","caption":"Icon Newsroom_news"},{"@type":"WebSite","@id":"https:\/\/dev.cometis.de\/de\/#website","url":"https:\/\/dev.cometis.de\/de\/","name":"cometis AG","description":"Deutschlands f\u00fchrende Investor Relations Agentur","publisher":{"@id":"https:\/\/dev.cometis.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.cometis.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dev.cometis.de\/de\/#organization","name":"cometis AG","alternateName":"Deutschlands f\u00fchrende Investor Relations Agentur","url":"https:\/\/dev.cometis.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dev.cometis.de\/de\/#\/schema\/logo\/image\/","url":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/01\/Cometis-Mobile-Logo-1.png","contentUrl":"https:\/\/dev.cometis.de\/wp-content\/uploads\/2022\/01\/Cometis-Mobile-Logo-1.png","width":171,"height":31,"caption":"cometis AG"},"image":{"@id":"https:\/\/dev.cometis.de\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/0f6ec71e9167dd48a24950f3cc6b2003","name":"Assistenz cometis AG","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dev.cometis.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d9db77bcddbfa0c99848135c21ae5b93?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d9db77bcddbfa0c99848135c21ae5b93?s=96&d=mm&r=g","caption":"Assistenz cometis AG"},"url":"https:\/\/dev.cometis.de\/de\/author\/assistenz-cometis-ag\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/posts\/16885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/users\/24813"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/comments?post=16885"}],"version-history":[{"count":0,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/posts\/16885\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/media\/54373"}],"wp:attachment":[{"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/media?parent=16885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/categories?post=16885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.cometis.de\/de\/wp-json\/wp\/v2\/tags?post=16885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}